{"id":10193,"date":"2017-01-20T11:35:28","date_gmt":"2017-01-20T10:35:28","guid":{"rendered":"https:\/\/www.circhimica.it\/prodotto\/consacrilic\/"},"modified":"2026-02-18T16:27:17","modified_gmt":"2026-02-18T15:27:17","slug":"consacrilic","status":"publish","type":"product","link":"https:\/\/www.circhimica.it\/en\/prodotto\/consacrilic\/","title":{"rendered":"CONSACRILIC"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; bottom_margin=&#8221;0&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_cta btn_style=&#8221;arrow-animation&#8221; heading_tag=&#8221;h4&#8243; link_type=&#8221;regular&#8221; button_color=&#8221;default&#8221; button_border_thickness=&#8221;0px&#8221; alignment=&#8221;left&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; display=&#8221;inline&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; link_text=&#8221;PRODUCT DESCRIPTION&#8221; margin_right=&#8221;20&#8243; url=&#8221;#descrizione&#8221;][nectar_cta btn_style=&#8221;arrow-animation&#8221; heading_tag=&#8221;h4&#8243; link_type=&#8221;regular&#8221; button_color=&#8221;default&#8221; button_border_thickness=&#8221;0px&#8221; alignment=&#8221;left&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; display=&#8221;inline&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; link_text=&#8221;EXAMPLES OF APPLICATION&#8221; margin_right=&#8221;20&#8243; url=&#8221;#esempi&#8221;][nectar_cta btn_style=&#8221;arrow-animation&#8221; heading_tag=&#8221;h4&#8243; link_type=&#8221;regular&#8221; button_color=&#8221;default&#8221; button_border_thickness=&#8221;0px&#8221; alignment=&#8221;left&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; display=&#8221;inline&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; link_text=&#8221;DOWNLOAD THE TECHNICAL MATERIAL&#8221; margin_right=&#8221;20&#8243; url=&#8221;#downloads&#8221;][nectar_cta btn_style=&#8221;arrow-animation&#8221; heading_tag=&#8221;h4&#8243; link_type=&#8221;regular&#8221; button_color=&#8221;default&#8221; button_border_thickness=&#8221;0px&#8221; alignment=&#8221;left&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; display=&#8221;inline&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; link_text=&#8221;REQUEST MORE INFORMATION&#8221; margin_right=&#8221;20&#8243; url=&#8221;#form&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#dff1fb&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;15&#8243; bottom_padding=&#8221;10&#8243; top_margin=&#8221;5&#8243; bottom_margin=&#8221;20&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;4810&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; img_link=&#8221;https:\/\/www.circhimica.it\/en\/facades-line\/&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;right&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;right&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;10188&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; img_link=&#8221;https:\/\/www.circhimica.it\/en\/facades-line\/&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;10183&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; img_link=&#8221;https:\/\/www.circhimica.it\/en\/voc-zero\/&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;4873&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; img_link=&#8221;https:\/\/www.circhimica.it\/en\/tag-prodotto-en\/base-acqua-en\/&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;none&#8221; equal_height=&#8221;yes&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;RANGE.&#8221; font_container=&#8221;tag:h2|font_size:1.5em|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;COMPATIBLE MATERIALS&#8221; font_container=&#8221;tag:h2|font_size:1.5em|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;METHOD OF APPLICATION&#8221; font_container=&#8221;tag:h2|font_size:1.5em|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;custom&#8221; column_margin_custom=&#8221;3px&#8221; equal_height=&#8221;yes&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;12901&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; img_link=&#8221;https:\/\/www.circhimica.it\/en\/gamma\/consolidants\/&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h6 style=\"text-align: center;\"><a href=\"https:\/\/www.circhimica.it\/en\/gamma\/consolidants\/\">CONSOLIDANTS<\/a><\/h6>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;12777&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; img_link=&#8221;https:\/\/www.circhimica.it\/en\/materiali-di-applicazione\/finiture-en\/&#8221;][vc_column_text css=&#8221;.vc_custom_1753946428659{margin-bottom: 8px !important;}&#8221; text_direction=&#8221;default&#8221;]\n<h6 style=\"text-align: center;\"><a href=\"https:\/\/www.circhimica.it\/en\/materiali-di-applicazione\/finiture-en\/\">FINISHES<\/a><\/h6>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;12921&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; img_link=&#8221;https:\/\/www.circhimica.it\/en\/materiali-di-applicazione\/intonaci-en\/&#8221;][vc_column_text css=&#8221;.vc_custom_1753946440336{margin-bottom: 8px !important;}&#8221; text_direction=&#8221;default&#8221;]\n<h6 style=\"text-align: center;\"><a href=\"https:\/\/www.circhimica.it\/en\/materiali-di-applicazione\/intonaci-en\/\">PLASTER<\/a><\/h6>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;12782&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; img_link=&#8221;https:\/\/www.circhimica.it\/en\/materiali-di-applicazione\/calce-en\/&#8221;][vc_column_text css=&#8221;.vc_custom_1753946411784{margin-bottom: 8px !important;}&#8221; text_direction=&#8221;default&#8221;]\n<h6 style=\"text-align: center;\"><a href=\"https:\/\/www.circhimica.it\/en\/materiali-di-applicazione\/calce-en\/\">LIME<\/a><\/h6>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;12543&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h6 style=\"text-align: center;\">BRUSH<\/h6>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;12631&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h6 style=\"text-align: center;\">NEBULIZER<\/h6>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; id=&#8221;descrizione&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;PRODUCT DESCRIPTION&#8221; font_container=&#8221;tag:h2|font_size:1.5em|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]Product based on <strong>micronized acrylic resins in aqueous micro-emulsion<\/strong>, particularly suitable for the <strong>insulating and consolidating treatment of absorbent chalky and\/or loose mineral surfaces<\/strong>. Thanks to its particular composition and the extremely small size of its particles, <strong>CONSACRILIC <\/strong>has a <strong>high penetration ability<\/strong> and carries out a <strong>strong consolidating action<\/strong>, both on surface and deep, acting as a binder on the material and eliminating any chalking problem.<\/p>\n<p>It also has the ability <strong>to make the absorption of the substrate extremely homogeneous<\/strong>, promoting adhesion and optimizing any over-painting and\/or finishing operations. <strong>CONSACRILIC <\/strong>does not alter the chromatic aspect of the support and does not substantially modify its breathability and permeability to water vapour, as well as having <strong>excellent resistance to UV rays<\/strong>.[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;none&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#dff1fb&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;10&#8243; bottom_padding=&#8221;5&#8243; left_padding_desktop=&#8221;20&#8243; right_padding_desktop=&#8221;20&#8243; bottom_margin=&#8221;10&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;ADVANTAGES&#8221; font_container=&#8221;tag:h2|font_size:1.5em|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;]<div class=\"nectar-fancy-ul\" data-list-icon=\"fa fa-plus\" data-animation=\"false\" data-animation-delay=\"0\" data-color=\"extra-color-2\" data-spacing=\"10px\" data-alignment=\"left\"> \n<ul>\n<li><strong>WATER BASED<\/strong>: Contains no harmful solvents.<\/li>\n<li><i class=\"icon-default-style fa fa-plus extra-color-2\"><\/i><strong>NANOTECHNOLOGICAL<\/strong>: Thanks to the nanoparticles the product has high penetration capacity.<\/li>\n<li><i class=\"icon-default-style fa fa-plus extra-color-2\"><\/i><strong>VOC = 0<\/strong>: Zero volatile organic emissions.<i class=\"icon-default-style fa fa-plus extra-color-2\"><\/i><\/li>\n<li><i class=\"icon-default-style fa fa-plus extra-color-2\"><\/i>High <strong>CONSOLIDATING <\/strong>and <strong>INSULATING <\/strong>power.<\/li>\n<li><i class=\"icon-default-style fa fa-plus extra-color-2\"><\/i><strong>UNIFORM ABSORPTION<\/strong>: Uniforms the absorption capacity of the treated surface.<\/li>\n<\/ul>\n <\/div>[\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; id=&#8221;esempi&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_video link=&#8221;https:\/\/www.youtube.com\/watch?v=p1g-dJeFBQo&#8221; css=&#8221;&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;APPLICATION VIDEO &#8211; CONSOLIDATION OF MATERIALS AND PLASTERS&#8221; font_container=&#8221;tag:h2|font_size:1.5em|text_align:left|line_height:1.2em&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;.vc_custom_1754039284420{margin-bottom: 20px !important;}&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]This application video provides an overview of our <strong>products for consolidating stone, brick, and plaster<\/strong>.<\/p>\n<p>We specifically illustrate the differences between our consolidating products, allowing the operator <strong>to always select the most suitable product<\/strong>.[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#dff1fb&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;10&#8243; bottom_padding=&#8221;20&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; id=&#8221;downloads&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_custom_heading text=&#8221;DOWNLOADS &#8211; TECHNICAL AND PROMOTIONAL MATERIAL&#8221; font_container=&#8221;tag:h2|font_size:1.5em|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][vc_column_text css=&#8221;.vc_custom_1744384490122{padding-right: 30px !important;}&#8221; text_direction=&#8221;default&#8221;]You can download our up-to-date technical material at any time, <strong>in PDF format, in all available languages for a given product<\/strong>.<br \/>\nIf you require <strong>more detailed information<\/strong> or our <strong>direct technical support<\/strong>, please send us a specific request by filling out the <strong>form <\/strong>below.[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;TECHNICAL DATA SHEET&#8221; font_container=&#8221;tag:h2|font_size:1.5em|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;center&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;12463&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; img_link_target=&#8221;_blank&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; img_link=&#8221;\/wp-content\/uploads\/2023\/07\/CONSACRILIC_ITA.pdf&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;12468&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;right&#8221; img_link_target=&#8221;_blank&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; img_link=&#8221;\/wp-content\/uploads\/2024\/06\/CONSACRILIC_ENG.pdf&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;12498&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;right&#8221; img_link_target=&#8221;_blank&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; img_link=&#8221;\/wp-content\/uploads\/2024\/06\/CONSACRILIC_ESP.pdf&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;12503&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;right&#8221; img_link_target=&#8221;_blank&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; img_link=&#8221;\/wp-content\/uploads\/2024\/06\/CONSACRILIC_POR.pdf&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;12508&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;right&#8221; img_link_target=&#8221;_blank&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; img_link=&#8221;\/wp-content\/uploads\/2024\/06\/CONSACRILIC_GRE.pdf&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][\/vc_row_inner][vc_custom_heading text=&#8221;SAFETY DATA SHEET&#8221; font_container=&#8221;tag:h2|font_size:1.5em|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;center&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;12463&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; img_link_target=&#8221;_blank&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; img_link=&#8221;\/wp-content\/uploads\/2026\/02\/Scheda-di-sicurezza-CONSACRILIC.pdf&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; id=&#8221;form&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;REQUEST MORE INFORMATION NOW &#8211; FILL OUT THIS FORM&#8221; font_container=&#8221;tag:h1|font_size:1.5em|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;]<noscript class=\"ninja-forms-noscript-message\">\n\tNotice: JavaScript is required for this content.<\/noscript>\n<div id=\"nf-form-10-cont\" class=\"nf-form-cont\" aria-live=\"polite\" aria-labelledby=\"nf-form-title-10\" aria-describedby=\"nf-form-errors-10\" role=\"form\">\n\n    <div class=\"nf-loading-spinner\"><\/div>\n\n<\/div>\n        <!-- That data is being printed as a workaround to page builders reordering the order of the scripts loaded-->\n        <script>var formDisplay=1;var nfForms=nfForms||[];var form=[];form.id='10';form.settings={\"objectType\":\"Form Setting\",\"editActive\":true,\"title\":\"INFORMATION REQUEST - General\",\"created_at\":\"2025-08-04 15:46:38\",\"default_label_pos\":\"left\",\"show_title\":\"0\",\"clear_complete\":\"1\",\"hide_complete\":\"1\",\"logged_in\":\"\",\"wrapper_class\":\"\",\"element_class\":\"\",\"key\":\"\",\"add_submit\":\"1\",\"changeEmailErrorMsg\":\"Please enter a valid email address!\",\"changeDateErrorMsg\":\"Please enter a valid date!\",\"confirmFieldErrorMsg\":\"These fields must match!\",\"fieldNumberNumMinError\":\"Number Min Error\",\"fieldNumberNumMaxError\":\"Number Max Error\",\"fieldNumberIncrementBy\":\"Please increment by \",\"formErrorsCorrectErrors\":\"Please correct errors before submitting this form.\",\"validateRequiredField\":\"This is a required field.\",\"honeypotHoneypotError\":\"Honeypot Error\",\"fieldsMarkedRequired\":\"Fields marked with an <span class=\\\"ninja-forms-req-symbol\\\">*<\\\/span> are required\",\"currency\":\"\",\"repeatable_fieldsets\":\"\",\"unique_field_error\":\"A form with this value has already been submitted.\",\"not_logged_in_msg\":\"\",\"sub_limit_msg\":\"The form has reached its submission limit.\",\"calculations\":[],\"formContentData\":[\"nb_i_campi_contrassegnati_con_sono_obbligatori_1648116034111\",\"nome_e_cognome_o_ragione_sociale_1648115325577\",\"tipologia_di_impresa_cliente_1744366418935\",\"city_1648115394347\",\"email_1648115409608\",\"phone_1648116570469\",\"hr_1648115499923\",\"tipologia_di_intervento_1744366483774\",\"scrivi_ulteriori_richieste_o_dettagli_sull_intervento_da_effettuare_1648115743086\",\"hr_1648115753742\",\"autorizzo_il_trattamento_dei_miei_dati_personali_ai_sensi_della_legge_196_03_sulla_privacy_1648115780227\",\"invia_richiesta_1648116001680\",\"hidden_1754315696073\"],\"drawerDisabled\":false,\"form_title_heading_level\":\"4\",\"allow_public_link\":0,\"embed_form\":\"\",\"objectDomain\":\"calculations\",\"ninjaForms\":\"Ninja Forms\",\"fieldTextareaRTEInsertLink\":\"Insert Link\",\"fieldTextareaRTEInsertMedia\":\"Insert Media\",\"fieldTextareaRTESelectAFile\":\"Select a file\",\"tableInsertRowAbove\":\"Insert Row Above\",\"tableInsertRowBelow\":\"Insert Row Below\",\"tableInsertColumnLeft\":\"Insert Column Left\",\"tableInsertColumnRight\":\"Insert Column Right\",\"tableDeleteRow\":\"Delete Row\",\"tableDeleteColumn\":\"Delete Column\",\"tableDeleteTable\":\"Delete Table\",\"tableLegacyNotice\":\"This content has tables in the old editor format. Custom styles are preserved until converted. Editing will update to the new format.\",\"tableLegacyConvert\":\"Convert Now\",\"tableInsertTable\":\"Insert Table\",\"dismiss\":\"Dismiss\",\"insertLink\":\"Insert Link\",\"formHoneypot\":\"If you are a human seeing this field, please leave it empty.\",\"fileUploadOldCodeFileUploadInProgress\":\"File Upload in Progress.\",\"fileUploadOldCodeFileUpload\":\"FILE UPLOAD\",\"currencySymbol\":\"&#36;\",\"thousands_sep\":\",\",\"decimal_point\":\".\",\"siteLocale\":\"en_US\",\"dateFormat\":\"m\\\/d\\\/Y\",\"startOfWeek\":\"1\",\"of\":\"of\",\"previousMonth\":\"Previous Month\",\"nextMonth\":\"Next Month\",\"months\":[\"January\",\"February\",\"March\",\"April\",\"May\",\"June\",\"July\",\"August\",\"September\",\"October\",\"November\",\"December\"],\"monthsShort\":[\"Jan\",\"Feb\",\"Mar\",\"Apr\",\"May\",\"Jun\",\"Jul\",\"Aug\",\"Sep\",\"Oct\",\"Nov\",\"Dec\"],\"weekdays\":[\"Sunday\",\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\"],\"weekdaysShort\":[\"Sun\",\"Mon\",\"Tue\",\"Wed\",\"Thu\",\"Fri\",\"Sat\"],\"weekdaysMin\":[\"Su\",\"Mo\",\"Tu\",\"We\",\"Th\",\"Fr\",\"Sa\"],\"recaptchaConsentMissing\":\"reCaptcha validation couldn&#039;t load.\",\"recaptchaMissingCookie\":\"reCaptcha v3 validation couldn&#039;t load the cookie needed to submit the form.\",\"recaptchaConsentEvent\":\"Accept reCaptcha cookies before sending the form.\",\"currency_symbol\":\"\",\"beforeForm\":\"\",\"beforeFields\":\"\",\"afterFields\":\"\",\"afterForm\":\"\"};form.fields=[{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":3,\"idAttribute\":\"id\",\"label\":\"Fields marked with * are mandatory.\",\"type\":\"html\",\"default\":\"<p><br><\\\/p>\",\"container_class\":\"\",\"element_class\":\"\",\"key\":\"nb_i_campi_contrassegnati_con_sono_obbligatori_1648116034111\",\"drawerDisabled\":false,\"field_label\":\"NB I campi contrassegnati con * sono obbligatori\",\"field_key\":\"nb_i_campi_contrassegnati_con_sono_obbligatori_1648116034111\",\"admin_label\":\"\",\"id\":117,\"beforeField\":\"\",\"afterField\":\"\",\"value\":\"<p><br><\\\/p>\",\"label_pos\":\"left\",\"parentType\":\"html\",\"element_templates\":[\"html\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":4,\"idAttribute\":\"id\",\"label\":\"First name and surname or company name\",\"type\":\"firstname\",\"key\":\"nome_e_cognome_o_ragione_sociale_1648115325577\",\"label_pos\":\"left\",\"required\":1,\"default\":\"\",\"placeholder\":\"\",\"container_class\":\"\",\"element_class\":\"\",\"admin_label\":\"\",\"help_text\":\"\",\"custom_name_attribute\":\"fname\",\"personally_identifiable\":1,\"value\":\"\",\"drawerDisabled\":\"\",\"field_label\":\"Nome e Cognome o Ragione Sociale\",\"field_key\":\"nome_e_cognome_o_ragione_sociale_1648115325577\",\"id\":113,\"beforeField\":\"\",\"afterField\":\"\",\"parentType\":\"firstname\",\"element_templates\":[\"firstname\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":5,\"idAttribute\":\"id\",\"label\":\"Type of business\\\/customer\",\"type\":\"listselect\",\"key\":\"tipologia_di_impresa_cliente_1744366418935\",\"label_pos\":\"left\",\"required\":1,\"options\":[{\"errors\":[],\"max_options\":0,\"label\":\"Construction Company\",\"value\":\"impresa-edile\",\"calc\":\"\",\"selected\":0,\"order\":0,\"settingModel\":{\"settings\":false,\"hide_merge_tags\":false,\"error\":false,\"name\":\"options\",\"type\":\"option-repeater\",\"label\":\"Options <a href=\\\"#\\\" class=\\\"nf-add-new\\\">Aggiungi nuovo<\\\/a> <a href=\\\"#\\\" class=\\\"extra nf-open-import-tooltip\\\"><i class=\\\"fa fa-sign-in\\\" aria-hidden=\\\"true\\\"><\\\/i> Importa<\\\/a>\",\"width\":\"full\",\"group\":\"\",\"value\":[{\"label\":\"Uno\",\"value\":\"uno\",\"calc\":\"\",\"selected\":0,\"order\":0},{\"label\":\"Due\",\"value\":\"due\",\"calc\":\"\",\"selected\":0,\"order\":1},{\"label\":\"Tre\",\"value\":\"tre\",\"calc\":\"\",\"selected\":0,\"order\":2}],\"columns\":{\"label\":{\"header\":\"Etichetta\",\"default\":\"\"},\"value\":{\"header\":\"Valore\",\"default\":\"\"},\"calc\":{\"header\":\"Calcolo\",\"default\":\"\"},\"selected\":{\"header\":\"<span class=\\\"dashicons dashicons-yes\\\"><\\\/span>\",\"default\":0}}}},{\"errors\":[],\"max_options\":0,\"label\":\"Restoration Company\",\"value\":\"impresa-di-restauro\",\"calc\":\"\",\"selected\":0,\"order\":1,\"settingModel\":{\"settings\":false,\"hide_merge_tags\":false,\"error\":false,\"name\":\"options\",\"type\":\"option-repeater\",\"label\":\"Options <a href=\\\"#\\\" class=\\\"nf-add-new\\\">Aggiungi nuovo<\\\/a> <a href=\\\"#\\\" class=\\\"extra nf-open-import-tooltip\\\"><i class=\\\"fa fa-sign-in\\\" aria-hidden=\\\"true\\\"><\\\/i> Importa<\\\/a>\",\"width\":\"full\",\"group\":\"\",\"value\":[{\"label\":\"Uno\",\"value\":\"uno\",\"calc\":\"\",\"selected\":0,\"order\":0},{\"label\":\"Due\",\"value\":\"due\",\"calc\":\"\",\"selected\":0,\"order\":1},{\"label\":\"Tre\",\"value\":\"tre\",\"calc\":\"\",\"selected\":0,\"order\":2}],\"columns\":{\"label\":{\"header\":\"Etichetta\",\"default\":\"\"},\"value\":{\"header\":\"Valore\",\"default\":\"\"},\"calc\":{\"header\":\"Calcolo\",\"default\":\"\"},\"selected\":{\"header\":\"<span class=\\\"dashicons dashicons-yes\\\"><\\\/span>\",\"default\":0}}}},{\"errors\":[],\"max_options\":0,\"label\":\"Designer \\\/ Professional\",\"value\":\"progettista-professionista\",\"calc\":\"\",\"selected\":0,\"order\":2,\"settingModel\":{\"settings\":false,\"hide_merge_tags\":false,\"error\":false,\"name\":\"options\",\"type\":\"option-repeater\",\"label\":\"Options <a href=\\\"#\\\" class=\\\"nf-add-new\\\">Aggiungi nuovo<\\\/a> <a href=\\\"#\\\" class=\\\"extra nf-open-import-tooltip\\\"><i class=\\\"fa fa-sign-in\\\" aria-hidden=\\\"true\\\"><\\\/i> Importa<\\\/a>\",\"width\":\"full\",\"group\":\"\",\"value\":[{\"label\":\"Uno\",\"value\":\"uno\",\"calc\":\"\",\"selected\":0,\"order\":0},{\"label\":\"Due\",\"value\":\"due\",\"calc\":\"\",\"selected\":0,\"order\":1},{\"label\":\"Tre\",\"value\":\"tre\",\"calc\":\"\",\"selected\":0,\"order\":2}],\"columns\":{\"label\":{\"header\":\"Etichetta\",\"default\":\"\"},\"value\":{\"header\":\"Valore\",\"default\":\"\"},\"calc\":{\"header\":\"Calcolo\",\"default\":\"\"},\"selected\":{\"header\":\"<span class=\\\"dashicons dashicons-yes\\\"><\\\/span>\",\"default\":0}}}},{\"errors\":[],\"max_options\":0,\"order\":3,\"new\":false,\"options\":[],\"label\":\"Retailer\",\"value\":\"rivenditore\",\"calc\":\"\",\"selected\":0,\"settingModel\":{\"settings\":false,\"hide_merge_tags\":false,\"error\":false,\"name\":\"options\",\"type\":\"option-repeater\",\"label\":\"Options <a href=\\\"#\\\" class=\\\"nf-add-new\\\">Aggiungi nuovo<\\\/a> <a href=\\\"#\\\" class=\\\"extra nf-open-import-tooltip\\\"><i class=\\\"fa fa-sign-in\\\" aria-hidden=\\\"true\\\"><\\\/i> Importa<\\\/a>\",\"width\":\"full\",\"group\":\"\",\"value\":[{\"label\":\"Uno\",\"value\":\"uno\",\"calc\":\"\",\"selected\":0,\"order\":0},{\"label\":\"Due\",\"value\":\"due\",\"calc\":\"\",\"selected\":0,\"order\":1},{\"label\":\"Tre\",\"value\":\"tre\",\"calc\":\"\",\"selected\":0,\"order\":2}],\"columns\":{\"label\":{\"header\":\"Etichetta\",\"default\":\"\"},\"value\":{\"header\":\"Valore\",\"default\":\"\"},\"calc\":{\"header\":\"Calcolo\",\"default\":\"\"},\"selected\":{\"header\":\"<span class=\\\"dashicons dashicons-yes\\\"><\\\/span>\",\"default\":0}}}},{\"errors\":[],\"max_options\":0,\"order\":4,\"new\":false,\"options\":[],\"label\":\"Private customer\",\"value\":\"cliente-privato\",\"calc\":\"\",\"selected\":0,\"settingModel\":{\"settings\":false,\"hide_merge_tags\":false,\"error\":false,\"name\":\"options\",\"type\":\"option-repeater\",\"label\":\"Options <a href=\\\"#\\\" class=\\\"nf-add-new\\\">Aggiungi nuovo<\\\/a> <a href=\\\"#\\\" class=\\\"extra nf-open-import-tooltip\\\"><i class=\\\"fa fa-sign-in\\\" aria-hidden=\\\"true\\\"><\\\/i> Importa<\\\/a>\",\"width\":\"full\",\"group\":\"\",\"value\":[{\"label\":\"Uno\",\"value\":\"uno\",\"calc\":\"\",\"selected\":0,\"order\":0},{\"label\":\"Due\",\"value\":\"due\",\"calc\":\"\",\"selected\":0,\"order\":1},{\"label\":\"Tre\",\"value\":\"tre\",\"calc\":\"\",\"selected\":0,\"order\":2}],\"columns\":{\"label\":{\"header\":\"Etichetta\",\"default\":\"\"},\"value\":{\"header\":\"Valore\",\"default\":\"\"},\"calc\":{\"header\":\"Calcolo\",\"default\":\"\"},\"selected\":{\"header\":\"<span class=\\\"dashicons dashicons-yes\\\"><\\\/span>\",\"default\":0}}}}],\"container_class\":\"\",\"element_class\":\"\",\"admin_label\":\"\",\"help_text\":\"\",\"drawerDisabled\":\"\",\"field_label\":\"Tipologia di impresa \\\/ cliente\",\"field_key\":\"tipologia_di_impresa_cliente_1744366418935\",\"id\":123,\"beforeField\":\"\",\"afterField\":\"\",\"value\":\"\",\"parentType\":\"list\",\"element_templates\":[\"listselect\",\"input\"],\"old_classname\":\"list-select\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":6,\"idAttribute\":\"id\",\"label\":\"City\",\"type\":\"city\",\"key\":\"city_1648115394347\",\"label_pos\":\"left\",\"required\":1,\"default\":\"\",\"placeholder\":\"\",\"container_class\":\"\",\"element_class\":\"\",\"input_limit\":\"\",\"input_limit_type\":\"characters\",\"input_limit_msg\":\"Remaining characters\",\"manual_key\":\"\",\"admin_label\":\"\",\"help_text\":\"\",\"mask\":\"\",\"custom_mask\":\"\",\"custom_name_attribute\":\"city\",\"personally_identifiable\":\"\",\"value\":\"\",\"drawerDisabled\":\"\",\"field_label\":\"Citt\\u00e0\",\"field_key\":\"city_1648115394347\",\"id\":114,\"beforeField\":\"\",\"afterField\":\"\",\"parentType\":\"city\",\"element_templates\":[\"city\",\"textbox\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":7,\"idAttribute\":\"id\",\"label\":\"Email\",\"type\":\"email\",\"key\":\"email_1648115409608\",\"label_pos\":\"left\",\"required\":1,\"default\":\"\",\"placeholder\":\"\",\"container_class\":\"\",\"element_class\":\"\",\"admin_label\":\"\",\"help_text\":\"\",\"custom_name_attribute\":\"email\",\"personally_identifiable\":1,\"value\":\"\",\"drawerDisabled\":\"\",\"field_label\":\"Email\",\"field_key\":\"email_1648115409608\",\"id\":115,\"beforeField\":\"\",\"afterField\":\"\",\"parentType\":\"email\",\"element_templates\":[\"email\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":8,\"idAttribute\":\"id\",\"label\":\"Phone\",\"type\":\"phone\",\"key\":\"phone_1648116570469\",\"label_pos\":\"left\",\"required\":\"\",\"default\":\"\",\"placeholder\":\"\",\"container_class\":\"\",\"element_class\":\"\",\"input_limit\":\"\",\"input_limit_type\":\"characters\",\"input_limit_msg\":\"Remaining characters\",\"manual_key\":\"\",\"admin_label\":\"\",\"help_text\":\"\",\"mask\":\"\",\"custom_mask\":\"\",\"custom_name_attribute\":\"phone\",\"personally_identifiable\":1,\"value\":\"\",\"drawerDisabled\":\"\",\"field_label\":\"Telefono\",\"field_key\":\"phone_1648116570469\",\"id\":122,\"beforeField\":\"\",\"afterField\":\"\",\"parentType\":\"textbox\",\"element_templates\":[\"tel\",\"textbox\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":9,\"idAttribute\":\"id\",\"label\":\"Divider\",\"type\":\"hr\",\"container_class\":\"\",\"element_class\":\"\",\"key\":\"hr_1648115499923\",\"drawerDisabled\":\"\",\"field_label\":\"Divisore\",\"field_key\":\"hr_1648115499923\",\"admin_label\":\"\",\"id\":116,\"beforeField\":\"\",\"afterField\":\"\",\"value\":\"\",\"label_pos\":\"left\",\"parentType\":\"hr\",\"element_templates\":[\"hr\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":10,\"idAttribute\":\"id\",\"label\":\"Type of intervention\",\"type\":\"listselect\",\"key\":\"tipologia_di_intervento_1744366483774\",\"label_pos\":\"left\",\"required\":\"\",\"container_class\":\"\",\"element_class\":\"\",\"admin_label\":\"\",\"help_text\":\"\",\"drawerDisabled\":\"\",\"field_label\":\"Tipologia di intervento\",\"field_key\":\"tipologia_di_intervento_1744366483774\",\"options\":[{\"errors\":[],\"max_options\":0,\"label\":\"Civil construction site\",\"value\":\"cantiere-di-edilizia-civile\",\"calc\":\"\",\"selected\":0,\"order\":0,\"settingModel\":{\"settings\":false,\"hide_merge_tags\":false,\"error\":false,\"name\":\"options\",\"type\":\"option-repeater\",\"label\":\"Options <a href=\\\"#\\\" class=\\\"nf-add-new\\\">Aggiungi nuovo<\\\/a> <a href=\\\"#\\\" class=\\\"extra nf-open-import-tooltip\\\"><i class=\\\"fa fa-sign-in\\\" aria-hidden=\\\"true\\\"><\\\/i> Importa<\\\/a>\",\"width\":\"full\",\"group\":\"\",\"value\":[{\"label\":\"Uno\",\"value\":\"uno\",\"calc\":\"\",\"selected\":0,\"order\":0},{\"label\":\"Due\",\"value\":\"due\",\"calc\":\"\",\"selected\":0,\"order\":1},{\"label\":\"Tre\",\"value\":\"tre\",\"calc\":\"\",\"selected\":0,\"order\":2}],\"columns\":{\"label\":{\"header\":\"Etichetta\",\"default\":\"\"},\"value\":{\"header\":\"Valore\",\"default\":\"\"},\"calc\":{\"header\":\"Calcolo\",\"default\":\"\"},\"selected\":{\"header\":\"<span class=\\\"dashicons dashicons-yes\\\"><\\\/span>\",\"default\":0}}}},{\"errors\":[],\"max_options\":0,\"label\":\"Renovation\\\/restoration work\",\"value\":\"intervento-di-ristrutturazione-ripristino\",\"calc\":\"\",\"selected\":0,\"order\":1,\"settingModel\":{\"settings\":false,\"hide_merge_tags\":false,\"error\":false,\"name\":\"options\",\"type\":\"option-repeater\",\"label\":\"Options <a href=\\\"#\\\" class=\\\"nf-add-new\\\">Aggiungi nuovo<\\\/a> <a href=\\\"#\\\" class=\\\"extra nf-open-import-tooltip\\\"><i class=\\\"fa fa-sign-in\\\" aria-hidden=\\\"true\\\"><\\\/i> Importa<\\\/a>\",\"width\":\"full\",\"group\":\"\",\"value\":[{\"label\":\"Uno\",\"value\":\"uno\",\"calc\":\"\",\"selected\":0,\"order\":0},{\"label\":\"Due\",\"value\":\"due\",\"calc\":\"\",\"selected\":0,\"order\":1},{\"label\":\"Tre\",\"value\":\"tre\",\"calc\":\"\",\"selected\":0,\"order\":2}],\"columns\":{\"label\":{\"header\":\"Etichetta\",\"default\":\"\"},\"value\":{\"header\":\"Valore\",\"default\":\"\"},\"calc\":{\"header\":\"Calcolo\",\"default\":\"\"},\"selected\":{\"header\":\"<span class=\\\"dashicons dashicons-yes\\\"><\\\/span>\",\"default\":0}}}},{\"errors\":[],\"max_options\":0,\"label\":\"Monumental restoration site\",\"value\":\"cantiere-di-restauro-monumentale\",\"calc\":\"\",\"selected\":0,\"order\":2,\"settingModel\":{\"settings\":false,\"hide_merge_tags\":false,\"error\":false,\"name\":\"options\",\"type\":\"option-repeater\",\"label\":\"Options <a href=\\\"#\\\" class=\\\"nf-add-new\\\">Aggiungi nuovo<\\\/a> <a href=\\\"#\\\" class=\\\"extra nf-open-import-tooltip\\\"><i class=\\\"fa fa-sign-in\\\" aria-hidden=\\\"true\\\"><\\\/i> Importa<\\\/a>\",\"width\":\"full\",\"group\":\"\",\"value\":[{\"label\":\"Uno\",\"value\":\"uno\",\"calc\":\"\",\"selected\":0,\"order\":0},{\"label\":\"Due\",\"value\":\"due\",\"calc\":\"\",\"selected\":0,\"order\":1},{\"label\":\"Tre\",\"value\":\"tre\",\"calc\":\"\",\"selected\":0,\"order\":2}],\"columns\":{\"label\":{\"header\":\"Etichetta\",\"default\":\"\"},\"value\":{\"header\":\"Valore\",\"default\":\"\"},\"calc\":{\"header\":\"Calcolo\",\"default\":\"\"},\"selected\":{\"header\":\"<span class=\\\"dashicons dashicons-yes\\\"><\\\/span>\",\"default\":0}}}}],\"id\":124,\"beforeField\":\"\",\"afterField\":\"\",\"value\":\"\",\"parentType\":\"list\",\"element_templates\":[\"listselect\",\"input\"],\"old_classname\":\"list-select\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":11,\"idAttribute\":\"id\",\"label\":\"Write any additional requests or details about the work to be carried out.\",\"type\":\"textarea\",\"key\":\"scrivi_ulteriori_richieste_o_dettagli_sull_intervento_da_effettuare_1648115743086\",\"label_pos\":\"left\",\"required\":\"\",\"default\":\"\",\"placeholder\":\"\",\"container_class\":\"\",\"element_class\":\"\",\"input_limit\":\"\",\"input_limit_type\":\"characters\",\"input_limit_msg\":\"Remaining characters\",\"manual_key\":\"\",\"admin_label\":\"\",\"help_text\":\"\",\"textarea_rte\":\"\",\"disable_rte_mobile\":\"\",\"textarea_media\":\"\",\"value\":\"\",\"drawerDisabled\":\"\",\"field_label\":\"Scrivi ulteriori richieste o dettagli sull'intervento da effettuare\",\"field_key\":\"scrivi_ulteriori_richieste_o_dettagli_sull_intervento_da_effettuare_1648115743086\",\"id\":118,\"beforeField\":\"\",\"afterField\":\"\",\"parentType\":\"textarea\",\"element_templates\":[\"textarea\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":12,\"idAttribute\":\"id\",\"label\":\"Divider\",\"type\":\"hr\",\"container_class\":\"\",\"element_class\":\"\",\"key\":\"hr_1648115753742\",\"drawerDisabled\":\"\",\"field_label\":\"Divisore\",\"field_key\":\"hr_1648115753742\",\"admin_label\":\"\",\"id\":119,\"beforeField\":\"\",\"afterField\":\"\",\"value\":\"\",\"label_pos\":\"left\",\"parentType\":\"hr\",\"element_templates\":[\"hr\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":13,\"idAttribute\":\"id\",\"label\":\"I authorise the processing of my personal data in accordance with Law 196\\\/03 on privacy.\",\"type\":\"checkbox\",\"key\":\"autorizzo_il_trattamento_dei_miei_dati_personali_ai_sensi_della_legge_196_03_sulla_privacy_1648115780227\",\"label_pos\":\"right\",\"required\":1,\"container_class\":\"\",\"element_class\":\"\",\"manual_key\":\"\",\"admin_label\":\"\",\"help_text\":\"\",\"default_value\":\"unchecked\",\"checked_value\":\"Selezionato\",\"unchecked_value\":\"Deselezionato\",\"checked_calc_value\":\"\",\"unchecked_calc_value\":\"\",\"drawerDisabled\":\"\",\"field_label\":\"Autorizzo Il Trattamento Dei Miei Dati Personali Ai Sensi Della Legge 196\\\/03 Sulla Privacy\",\"field_key\":\"autorizzo_il_trattamento_dei_miei_dati_personali_ai_sensi_della_legge_196_03_sulla_privacy_1648115780227\",\"id\":120,\"beforeField\":\"\",\"afterField\":\"\",\"value\":\"\",\"parentType\":\"checkbox\",\"element_templates\":[\"checkbox\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":14,\"idAttribute\":\"id\",\"type\":\"submit\",\"label\":\"Send Request\",\"processing_label\":\"Treatment\",\"container_class\":\"\",\"element_class\":\"\",\"key\":\"invia_richiesta_1648116001680\",\"drawerDisabled\":\"\",\"field_label\":\"Invia Richiesta\",\"field_key\":\"invia_richiesta_1648116001680\",\"admin_label\":\"\",\"id\":121,\"beforeField\":\"\",\"afterField\":\"\",\"value\":\"\",\"label_pos\":\"left\",\"parentType\":\"textbox\",\"element_templates\":[\"submit\",\"button\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap-no-label\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":15,\"idAttribute\":\"id\",\"type\":\"hidden\",\"label\":\"Nascondi\",\"key\":\"hidden_1754315696073\",\"default\":\"\",\"admin_label\":\"\",\"id\":126,\"beforeField\":\"\",\"afterField\":\"\",\"value\":\"\",\"label_pos\":\"left\",\"parentType\":\"hidden\",\"element_templates\":[\"hidden\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap-no-label\"}];nfForms.push(form);<\/script>\n        [\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>High penetration acrylic consolidant and insulator for loose mineral surfaces<\/p>\n","protected":false},"featured_media":10720,"comment_status":"open","ping_status":"closed","template":"","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0},"product_brand":[],"product_cat":[656,283,282],"product_tag":[483,482,284],"class_list":{"0":"post-10193","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-coats-restoration-and-protection","7":"product_cat-facciate-consolidant-en","8":"product_cat-consolidamento-intonaci-en","9":"product_tag-sicuro_operatore-en","10":"product_tag-voczero-en","11":"product_tag-base-acqua-en","12":"pa_gamma-consolidants","13":"pa_linea-prodotto-facciate-en","14":"pa_materiali-di-applicazione-calce-en","15":"pa_materiali-di-applicazione-intonaci-en","16":"pa_materiali-di-applicazione-finiture-en","18":"first","19":"instock","20":"shipping-taxable","21":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/www.circhimica.it\/en\/wp-json\/wp\/v2\/product\/10193","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.circhimica.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.circhimica.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.circhimica.it\/en\/wp-json\/wp\/v2\/comments?post=10193"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.circhimica.it\/en\/wp-json\/wp\/v2\/media\/10720"}],"wp:attachment":[{"href":"https:\/\/www.circhimica.it\/en\/wp-json\/wp\/v2\/media?parent=10193"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.circhimica.it\/en\/wp-json\/wp\/v2\/product_brand?post=10193"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.circhimica.it\/en\/wp-json\/wp\/v2\/product_cat?post=10193"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.circhimica.it\/en\/wp-json\/wp\/v2\/product_tag?post=10193"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}