{"id":14190,"date":"2026-03-04T11:58:47","date_gmt":"2026-03-04T10:58:47","guid":{"rendered":"https:\/\/www.circhimica.it\/prodotto\/pav-lux\/"},"modified":"2026-05-19T16:09:59","modified_gmt":"2026-05-19T14:09:59","slug":"pav-lux","status":"publish","type":"product","link":"https:\/\/www.circhimica.it\/pt-pt\/prodotto\/pav-lux\/","title":{"rendered":"PAV LUX"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; bottom_margin=&#8221;0&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_cta btn_style=&#8221;arrow-animation&#8221; heading_tag=&#8221;h5&#8243; link_type=&#8221;regular&#8221; button_color=&#8221;default&#8221; button_border_thickness=&#8221;0px&#8221; alignment=&#8221;left&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; display=&#8221;inline&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; link_text=&#8221;DESCRI\u00c7\u00c3O DO PRODUTO&#8221; margin_right=&#8221;20&#8243; url=&#8221;#descrizione&#8221;][nectar_cta btn_style=&#8221;arrow-animation&#8221; heading_tag=&#8221;h5&#8243; link_type=&#8221;regular&#8221; button_color=&#8221;default&#8221; button_border_thickness=&#8221;0px&#8221; alignment=&#8221;left&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; display=&#8221;inline&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; link_text=&#8221;DESCARREGA MATERIAL T\u00c9CNICO&#8221; margin_right=&#8221;20&#8243; url=&#8221;#downloads&#8221;][nectar_cta btn_style=&#8221;arrow-animation&#8221; heading_tag=&#8221;h5&#8243; link_type=&#8221;regular&#8221; button_color=&#8221;default&#8221; button_border_thickness=&#8221;0px&#8221; alignment=&#8221;left&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; display=&#8221;inline&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; link_text=&#8221;SOLICITE MAIS INFORMA\u00c7\u00d5ES&#8221; margin_right=&#8221;20&#8243; url=&#8221;#form&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#dff1fb&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;15&#8243; bottom_padding=&#8221;10&#8243; top_margin=&#8221;5&#8243; bottom_margin=&#8221;20&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;4802&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; img_link=&#8221;https:\/\/www.circhimica.it\/pt-pt\/linea-pisos\/&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;right&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;right&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;4873&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; img_link=&#8221;https:\/\/www.circhimica.it\/pt-pt\/tag-prodotto-pt\/base-acqua-pt\/&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;none&#8221; equal_height=&#8221;yes&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;GAMA&#8221; font_container=&#8221;tag:h2|font_size:1.5em|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;MATERIAIS COMPAT\u00cdVEIS&#8221; font_container=&#8221;tag:h2|font_size:1.5em|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;MODOS DE APLICA\u00c7\u00c3O&#8221; font_container=&#8221;tag:h2|font_size:1.5em|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;custom&#8221; column_margin_custom=&#8221;3px&#8221; equal_height=&#8221;yes&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;12553&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; img_link=&#8221;https:\/\/www.circhimica.it\/pt-pt\/gamma\/limpadores\/&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h6 style=\"text-align: center;\"><a href=\"https:\/\/www.circhimica.it\/pt-pt\/gamma\/limpadores\/\">LIMPADORES<\/a><\/h6>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;12513&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; img_link=&#8221;\/?pa_materiali-di-applicazione=gres&#8221;][vc_column_text css=&#8221;.vc_custom_1753946404891{margin-bottom: 8px !important;}&#8221; text_direction=&#8221;default&#8221;]\n<h6 style=\"text-align: center;\"><a href=\"\/?pa_materiali-di-applicazione=gres\">GRES<\/a><\/h6>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;12601&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; img_link=&#8221;https:\/\/www.circhimica.it\/pt-pt\/materiali-di-applicazione\/cotto-pt\/&#8221;][vc_column_text css=&#8221;.vc_custom_1753946423003{margin-bottom: 8px !important;}&#8221; text_direction=&#8221;default&#8221;]\n<h6 style=\"text-align: center;\">TERRACOTA<\/h6>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;12518&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; img_link=&#8221;https:\/\/www.circhimica.it\/pt-pt\/materiali-di-applicazione\/pietra-calcarea-pt\/&#8221;][vc_column_text css=&#8221;.vc_custom_1753946375935{margin-bottom: 8px !important;}&#8221; text_direction=&#8221;default&#8221;]\n<h6 style=\"text-align: center;\"><a href=\"https:\/\/www.circhimica.it\/pt-pt\/materiali-di-applicazione\/pietra-calcarea-pt\/\">CALC\u00c1RIO <\/a><\/h6>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;12523&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; img_link=&#8221;https:\/\/www.circhimica.it\/pt-pt\/materiali-di-applicazione\/pietre-silicee-pt\/&#8221;][vc_column_text css=&#8221;.vc_custom_1753946384932{margin-bottom: 8px !important;}&#8221; text_direction=&#8221;default&#8221;]\n<h6 style=\"text-align: center;\"><a href=\"https:\/\/www.circhimica.it\/pt-pt\/materiali-di-applicazione\/pietre-silicee-pt\/\">PEDRA DE SILICONE<\/a><\/h6>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;12941&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h6 style=\"text-align: center;\">MOP<\/h6>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;12946&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h6 style=\"text-align: center;\">M\u00c1QUINAS MONODISCO<\/h6>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; id=&#8221;descrizione&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;DESCRI\u00c7\u00c3O DO PRODUTO&#8221; font_container=&#8221;tag:h2|font_size:1.5em|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<strong>PAV LUX<\/strong> \u00e9 um <strong>produto de limpeza de manuten\u00e7\u00e3o neutro<\/strong> constitu\u00eddo por uma solu\u00e7\u00e3o aquosa com <strong>aroma a pinho<\/strong> de tensioactivos com diferentes cargas i\u00f3nicas e solventes, concebido para a <strong>limpeza e manuten\u00e7\u00e3o de pavimentos em geral, polidos ou tratados com acabamentos<\/strong>.<\/p>\n<p>Remove eficaz e rapidamente a sujidade das superf\u00edcies protegidas. <strong>PAV LUX<\/strong> tem um <strong>poder de polimento especial<\/strong> e pode ser utilizado com uma <strong>m\u00e1quina de disco \u00fanico para polir superf\u00edcies enceradas<\/strong>, mesmo com o m\u00e9todo &#8220;Spray-Cleaning&#8221;. Exerce igualmente uma <strong>a\u00e7\u00e3o antiest\u00e1tica contra a sujidade<\/strong>.[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;none&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#dff1fb&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;10&#8243; bottom_padding=&#8221;5&#8243; left_padding_desktop=&#8221;20&#8243; right_padding_desktop=&#8221;20&#8243; bottom_margin=&#8221;10&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;AS VANTAGENS DO PAV LUX&#8221; font_container=&#8221;tag:h2|font_size:1.5em|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;]<div class=\"nectar-fancy-ul\" data-list-icon=\"fa fa-plus\" data-animation=\"false\" data-animation-delay=\"0\" data-color=\"extra-color-2\" data-spacing=\"10px\" data-alignment=\"left\"> \n<ul>\n<li>Produto neutro adequado para <strong>TODOS OS TIPOS DE PAVIMENTOS<\/strong>.<\/li>\n<li><i class=\"icon-default-style fa fa-plus extra-color-2\"><\/i>Remove eficazmente a sujidade de <strong>SUPERF\u00cdCIES PROTEGIDAS<\/strong>.<\/li>\n<li><i class=\"icon-default-style fa fa-plus extra-color-2\"><\/i>Poder especial de <strong>POLIMENTO<\/strong>.<\/li>\n<li><i class=\"icon-default-style fa fa-plus extra-color-2\"><\/i><strong>A\u00c7\u00c3O ANTIEST\u00c1TICA<\/strong> contra a acumula\u00e7\u00e3o de p\u00f3.<\/li>\n<li><i class=\"icon-default-style fa fa-plus extra-color-2\"><\/i>Utiliz\u00e1vel com <strong>MONOESPAV\u00c3O <\/strong>com <strong>m\u00e9todo SPRAY-CLEANING<\/strong>.<\/li>\n<\/ul>\n <\/div>[\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#dff1fb&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;10&#8243; bottom_padding=&#8221;20&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; id=&#8221;downloads&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_custom_heading text=&#8221;DESCARREGAMENTOS &#8211; MATERIAL T\u00c9CNICO E PROMOCIONAL&#8221; font_container=&#8221;tag:h2|font_size:1.5em|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][vc_column_text css=&#8221;.vc_custom_1744384490122{padding-right: 30px !important;}&#8221; text_direction=&#8221;default&#8221;]Pode descarregar o nosso material t\u00e9cnico atualizado a qualquer momento, <strong>em formato PDF, em todos os idiomas dispon\u00edveis para um produto espec\u00edfico<\/strong>.<br \/>\nSe necessitar de <strong>informa\u00e7\u00f5es mais detalhadas<\/strong> ou das nossas <strong>informa\u00e7\u00f5es t\u00e9cnicas diretas<\/strong>, envie-nos um pedido espec\u00edfico atrav\u00e9s do <strong>formul\u00e1rio <\/strong>abaixo.[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;FICHA T\u00c9CNICA&#8221; font_container=&#8221;tag:h2|font_size:1.5em|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;center&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;12463&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; img_link_target=&#8221;_blank&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; img_link=&#8221;https:\/\/www.circhimica.it\/wp-content\/uploads\/2025\/10\/PAV-LUX_ITA.pdf&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;12468&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;right&#8221; img_link_target=&#8221;_blank&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; img_link=&#8221;https:\/\/www.circhimica.it\/wp-content\/uploads\/2025\/10\/PAV-LUX_ENG.pdf&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;12498&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;right&#8221; img_link_target=&#8221;_blank&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; img_link=&#8221;https:\/\/www.circhimica.it\/wp-content\/uploads\/2025\/10\/PAV-LUX_ESP.pdf&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;12503&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;right&#8221; img_link_target=&#8221;_blank&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; img_link=&#8221;https:\/\/www.circhimica.it\/wp-content\/uploads\/2025\/10\/PAV-LUX_POR.pdf&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;12508&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;right&#8221; img_link_target=&#8221;_blank&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; img_link=&#8221;https:\/\/www.circhimica.it\/wp-content\/uploads\/2025\/10\/PAV-LUX_GRE.pdf&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][\/vc_row_inner][vc_custom_heading text=&#8221;FICHA DE SEGURAN\u00c7A&#8221; font_container=&#8221;tag:h2|font_size:1.5em|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;center&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;12463&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; img_link_target=&#8221;_blank&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; img_link=&#8221;\/wp-content\/uploads\/2026\/02\/Scheda-di-sicurezza-PAV-LUX.pdf&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; id=&#8221;form&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;SOLICITE MAIS INFORMA\u00c7\u00d5ES AGORA MESMO &#8211; PREENCHA ESTE FORMUL\u00c1RIO&#8221; font_container=&#8221;tag:h1|font_size:1.5em|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;]<noscript class=\"ninja-forms-noscript-message\">\n\tAviso: Este conte\u00fado necessita do JavaScript.<\/noscript>\n<div id=\"nf-form-10-cont\" class=\"nf-form-cont\" aria-live=\"polite\" aria-labelledby=\"nf-form-title-10\" aria-describedby=\"nf-form-errors-10\" role=\"form\">\n\n    <div class=\"nf-loading-spinner\"><\/div>\n\n<\/div>\n        <!-- That data is being printed as a workaround to page builders reordering the order of the scripts loaded-->\n        <script>var formDisplay=1;var nfForms=nfForms||[];var form=[];form.id='10';form.settings={\"ninjaForms\":\"Ninja Forms\",\"changeEmailErrorMsg\":\"Introduza um endere\\u00e7o de correio eletr\\u00f3nico v\\u00e1lido!\",\"changeDateErrorMsg\":\"Please enter a valid date!\",\"confirmFieldErrorMsg\":\"Estes campos n\\u00e3o coincidem!\",\"fieldNumberNumMinError\":\"Erro de n\\u00famero m\\u00ednimo\",\"fieldNumberNumMaxError\":\"Erro de n\\u00famero m\\u00e1ximo\",\"fieldNumberIncrementBy\":\"Aumente em \",\"fieldTextareaRTEInsertLink\":\"Inserir hiperliga\\u00e7\\u00e3o\",\"fieldTextareaRTEInsertMedia\":\"Inserir multim\\u00e9dia\",\"fieldTextareaRTESelectAFile\":\"Selecione um ficheiro\",\"tableInsertRowAbove\":\"Insert Row Above\",\"tableInsertRowBelow\":\"Insert Row Below\",\"tableInsertColumnLeft\":\"Insert Column Left\",\"tableInsertColumnRight\":\"Insert Column Right\",\"tableDeleteRow\":\"Delete Row\",\"tableDeleteColumn\":\"Delete Column\",\"tableDeleteTable\":\"Delete Table\",\"tableLegacyNotice\":\"This content has tables in the old editor format. Custom styles are preserved until converted. Editing will update to the new format.\",\"tableLegacyConvert\":\"Convert Now\",\"tableInsertTable\":\"Insert Table\",\"dismiss\":\"Ignorar\",\"insertLink\":\"Inserir hiperliga\\u00e7\\u00e3o\",\"formErrorsCorrectErrors\":\"Corrija os erros antes de submeter este formul\\u00e1rio.\",\"formHoneypot\":\"Se for humano e estiver a ver este campo, deixe-o em branco.\",\"validateRequiredField\":\"Este campo \\u00e9 obrigat\\u00f3rio.\",\"honeypotHoneypotError\":\"Erro do pote de mel\",\"fileUploadOldCodeFileUploadInProgress\":\"Carregamento do ficheiro em curso.\",\"fileUploadOldCodeFileUpload\":\"CARREGAMENTO DO FICHEIRO\",\"currencySymbol\":\"&#36;\",\"fieldsMarkedRequired\":\"Os campos assinalados com um <span class=\\\"ninja-forms-req-symbol\\\">*<\\\/span> s\\u00e3o obrigat\\u00f3rios\",\"thousands_sep\":\".\",\"decimal_point\":\",\",\"siteLocale\":\"pt_PT\",\"dateFormat\":\"m\\\/d\\\/Y\",\"startOfWeek\":\"1\",\"of\":\"de\",\"previousMonth\":\"Previous Month\",\"nextMonth\":\"Next Month\",\"months\":[\"January\",\"February\",\"March\",\"April\",\"May\",\"June\",\"July\",\"August\",\"September\",\"October\",\"November\",\"December\"],\"monthsShort\":[\"Jan\",\"Feb\",\"Mar\",\"Apr\",\"May\",\"Jun\",\"Jul\",\"Aug\",\"Sep\",\"Oct\",\"Nov\",\"Dec\"],\"weekdays\":[\"Sunday\",\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\"],\"weekdaysShort\":[\"Sun\",\"Mon\",\"Tue\",\"Wed\",\"Thu\",\"Fri\",\"Sat\"],\"weekdaysMin\":[\"Su\",\"Mo\",\"Tu\",\"We\",\"Th\",\"Fr\",\"Sa\"],\"recaptchaConsentMissing\":\"reCaptcha validation couldn&#039;t load.\",\"recaptchaMissingCookie\":\"reCaptcha v3 validation couldn&#039;t load the cookie needed to submit the form.\",\"recaptchaConsentEvent\":\"Accept reCaptcha cookies before sending the form.\",\"hourPlaceholder\":\"Hour\",\"minutePlaceholder\":\"Minute\",\"am\":\"AM\",\"pm\":\"PM\",\"objectType\":\"Form Setting\",\"editActive\":true,\"title\":\"SOLICITA\\u00c7\\u00c3O DE INFORMA\\u00c7\\u00d5ES - Geral\",\"created_at\":\"2025-08-04 15:46:38\",\"default_label_pos\":\"left\",\"show_title\":\"0\",\"clear_complete\":\"1\",\"hide_complete\":\"1\",\"logged_in\":\"\",\"wrapper_class\":\"\",\"element_class\":\"\",\"key\":\"\",\"add_submit\":\"1\",\"currency\":\"\",\"repeatable_fieldsets\":\"\",\"unique_field_error\":\"Um formul\\u00e1rio com este valor j\\u00e1 foi enviado.\",\"not_logged_in_msg\":\"\",\"sub_limit_msg\":\"O formul\\u00e1rio atingiu o limite de envios.\",\"calculations\":[],\"formContentData\":[\"nb_i_campi_contrassegnati_con_sono_obbligatori_1648116034111\",\"nome_e_cognome_o_ragione_sociale_1648115325577\",\"tipologia_di_impresa_cliente_1744366418935\",\"city_1648115394347\",\"email_1648115409608\",\"phone_1648116570469\",\"hr_1648115499923\",\"tipologia_di_intervento_1744366483774\",\"scrivi_ulteriori_richieste_o_dettagli_sull_intervento_da_effettuare_1648115743086\",\"hr_1648115753742\",\"autorizzo_il_trattamento_dei_miei_dati_personali_ai_sensi_della_legge_196_03_sulla_privacy_1648115780227\",\"invia_richiesta_1648116001680\",\"hidden_1754315696073\"],\"drawerDisabled\":false,\"form_title_heading_level\":\"4\",\"allow_public_link\":0,\"embed_form\":\"\",\"objectDomain\":\"calculations\",\"currency_symbol\":\"\",\"beforeForm\":\"\",\"beforeFields\":\"\",\"afterFields\":\"\",\"afterForm\":\"\"};form.fields=[{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":3,\"idAttribute\":\"id\",\"label\":\"Os campos marcados com * s\\u00e3o obrigat\\u00f3rios\",\"type\":\"html\",\"default\":\"<p><br><\\\/p>\",\"container_class\":\"\",\"element_class\":\"\",\"key\":\"nb_i_campi_contrassegnati_con_sono_obbligatori_1648116034111\",\"drawerDisabled\":false,\"field_label\":\"NB I campi contrassegnati con * sono obbligatori\",\"field_key\":\"nb_i_campi_contrassegnati_con_sono_obbligatori_1648116034111\",\"admin_label\":\"\",\"id\":117,\"beforeField\":\"\",\"afterField\":\"\",\"value\":\"<p><br><\\\/p>\",\"label_pos\":\"left\",\"parentType\":\"html\",\"element_templates\":[\"html\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":4,\"idAttribute\":\"id\",\"label\":\"Nome e Apelido ou Raz\\u00e3o Social\",\"type\":\"firstname\",\"key\":\"nome_e_cognome_o_ragione_sociale_1648115325577\",\"label_pos\":\"left\",\"required\":1,\"default\":\"\",\"placeholder\":\"\",\"container_class\":\"\",\"element_class\":\"\",\"admin_label\":\"\",\"help_text\":\"\",\"custom_name_attribute\":\"fname\",\"personally_identifiable\":1,\"value\":\"\",\"drawerDisabled\":\"\",\"field_label\":\"Nome e Cognome o Ragione Sociale\",\"field_key\":\"nome_e_cognome_o_ragione_sociale_1648115325577\",\"id\":113,\"beforeField\":\"\",\"afterField\":\"\",\"parentType\":\"firstname\",\"element_templates\":[\"firstname\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":5,\"idAttribute\":\"id\",\"label\":\"Tipo de empresa\\\/cliente\",\"type\":\"listselect\",\"key\":\"tipologia_di_impresa_cliente_1744366418935\",\"label_pos\":\"left\",\"required\":1,\"options\":[{\"errors\":[],\"max_options\":0,\"label\":\"Empresa de constru\\u00e7\\u00e3o civil\",\"value\":\"impresa-edile\",\"calc\":\"\",\"selected\":0,\"order\":0,\"settingModel\":{\"settings\":false,\"hide_merge_tags\":false,\"error\":false,\"name\":\"options\",\"type\":\"option-repeater\",\"label\":\"Options <a href=\\\"#\\\" class=\\\"nf-add-new\\\">Aggiungi nuovo<\\\/a> <a href=\\\"#\\\" class=\\\"extra nf-open-import-tooltip\\\"><i class=\\\"fa fa-sign-in\\\" aria-hidden=\\\"true\\\"><\\\/i> Importa<\\\/a>\",\"width\":\"full\",\"group\":\"\",\"value\":[{\"label\":\"Uno\",\"value\":\"uno\",\"calc\":\"\",\"selected\":0,\"order\":0},{\"label\":\"Due\",\"value\":\"due\",\"calc\":\"\",\"selected\":0,\"order\":1},{\"label\":\"Tre\",\"value\":\"tre\",\"calc\":\"\",\"selected\":0,\"order\":2}],\"columns\":{\"label\":{\"header\":\"Etichetta\",\"default\":\"\"},\"value\":{\"header\":\"Valore\",\"default\":\"\"},\"calc\":{\"header\":\"Calcolo\",\"default\":\"\"},\"selected\":{\"header\":\"<span class=\\\"dashicons dashicons-yes\\\"><\\\/span>\",\"default\":0}}}},{\"errors\":[],\"max_options\":0,\"label\":\"Empresa de Restauro\",\"value\":\"impresa-di-restauro\",\"calc\":\"\",\"selected\":0,\"order\":1,\"settingModel\":{\"settings\":false,\"hide_merge_tags\":false,\"error\":false,\"name\":\"options\",\"type\":\"option-repeater\",\"label\":\"Options <a href=\\\"#\\\" class=\\\"nf-add-new\\\">Aggiungi nuovo<\\\/a> <a href=\\\"#\\\" class=\\\"extra nf-open-import-tooltip\\\"><i class=\\\"fa fa-sign-in\\\" aria-hidden=\\\"true\\\"><\\\/i> Importa<\\\/a>\",\"width\":\"full\",\"group\":\"\",\"value\":[{\"label\":\"Uno\",\"value\":\"uno\",\"calc\":\"\",\"selected\":0,\"order\":0},{\"label\":\"Due\",\"value\":\"due\",\"calc\":\"\",\"selected\":0,\"order\":1},{\"label\":\"Tre\",\"value\":\"tre\",\"calc\":\"\",\"selected\":0,\"order\":2}],\"columns\":{\"label\":{\"header\":\"Etichetta\",\"default\":\"\"},\"value\":{\"header\":\"Valore\",\"default\":\"\"},\"calc\":{\"header\":\"Calcolo\",\"default\":\"\"},\"selected\":{\"header\":\"<span class=\\\"dashicons dashicons-yes\\\"><\\\/span>\",\"default\":0}}}},{\"errors\":[],\"max_options\":0,\"label\":\"Projetista \\\/ Profissional\",\"value\":\"progettista-professionista\",\"calc\":\"\",\"selected\":0,\"order\":2,\"settingModel\":{\"settings\":false,\"hide_merge_tags\":false,\"error\":false,\"name\":\"options\",\"type\":\"option-repeater\",\"label\":\"Options <a href=\\\"#\\\" class=\\\"nf-add-new\\\">Aggiungi nuovo<\\\/a> <a href=\\\"#\\\" class=\\\"extra nf-open-import-tooltip\\\"><i class=\\\"fa fa-sign-in\\\" aria-hidden=\\\"true\\\"><\\\/i> Importa<\\\/a>\",\"width\":\"full\",\"group\":\"\",\"value\":[{\"label\":\"Uno\",\"value\":\"uno\",\"calc\":\"\",\"selected\":0,\"order\":0},{\"label\":\"Due\",\"value\":\"due\",\"calc\":\"\",\"selected\":0,\"order\":1},{\"label\":\"Tre\",\"value\":\"tre\",\"calc\":\"\",\"selected\":0,\"order\":2}],\"columns\":{\"label\":{\"header\":\"Etichetta\",\"default\":\"\"},\"value\":{\"header\":\"Valore\",\"default\":\"\"},\"calc\":{\"header\":\"Calcolo\",\"default\":\"\"},\"selected\":{\"header\":\"<span class=\\\"dashicons dashicons-yes\\\"><\\\/span>\",\"default\":0}}}},{\"errors\":[],\"max_options\":0,\"order\":3,\"new\":false,\"options\":[],\"label\":\"Rivenditore\",\"value\":\"rivenditore\",\"calc\":\"\",\"selected\":0,\"settingModel\":{\"settings\":false,\"hide_merge_tags\":false,\"error\":false,\"name\":\"options\",\"type\":\"option-repeater\",\"label\":\"Options <a href=\\\"#\\\" class=\\\"nf-add-new\\\">Aggiungi nuovo<\\\/a> <a href=\\\"#\\\" class=\\\"extra nf-open-import-tooltip\\\"><i class=\\\"fa fa-sign-in\\\" aria-hidden=\\\"true\\\"><\\\/i> Importa<\\\/a>\",\"width\":\"full\",\"group\":\"\",\"value\":[{\"label\":\"Uno\",\"value\":\"uno\",\"calc\":\"\",\"selected\":0,\"order\":0},{\"label\":\"Due\",\"value\":\"due\",\"calc\":\"\",\"selected\":0,\"order\":1},{\"label\":\"Tre\",\"value\":\"tre\",\"calc\":\"\",\"selected\":0,\"order\":2}],\"columns\":{\"label\":{\"header\":\"Etichetta\",\"default\":\"\"},\"value\":{\"header\":\"Valore\",\"default\":\"\"},\"calc\":{\"header\":\"Calcolo\",\"default\":\"\"},\"selected\":{\"header\":\"<span class=\\\"dashicons dashicons-yes\\\"><\\\/span>\",\"default\":0}}}},{\"errors\":[],\"max_options\":0,\"order\":4,\"new\":false,\"options\":[],\"label\":\"Cliente particular\",\"value\":\"cliente-privato\",\"calc\":\"\",\"selected\":0,\"settingModel\":{\"settings\":false,\"hide_merge_tags\":false,\"error\":false,\"name\":\"options\",\"type\":\"option-repeater\",\"label\":\"Options <a href=\\\"#\\\" class=\\\"nf-add-new\\\">Aggiungi nuovo<\\\/a> <a href=\\\"#\\\" class=\\\"extra nf-open-import-tooltip\\\"><i class=\\\"fa fa-sign-in\\\" aria-hidden=\\\"true\\\"><\\\/i> Importa<\\\/a>\",\"width\":\"full\",\"group\":\"\",\"value\":[{\"label\":\"Uno\",\"value\":\"uno\",\"calc\":\"\",\"selected\":0,\"order\":0},{\"label\":\"Due\",\"value\":\"due\",\"calc\":\"\",\"selected\":0,\"order\":1},{\"label\":\"Tre\",\"value\":\"tre\",\"calc\":\"\",\"selected\":0,\"order\":2}],\"columns\":{\"label\":{\"header\":\"Etichetta\",\"default\":\"\"},\"value\":{\"header\":\"Valore\",\"default\":\"\"},\"calc\":{\"header\":\"Calcolo\",\"default\":\"\"},\"selected\":{\"header\":\"<span class=\\\"dashicons dashicons-yes\\\"><\\\/span>\",\"default\":0}}}}],\"container_class\":\"\",\"element_class\":\"\",\"admin_label\":\"\",\"help_text\":\"\",\"drawerDisabled\":\"\",\"field_label\":\"Tipologia di impresa \\\/ cliente\",\"field_key\":\"tipologia_di_impresa_cliente_1744366418935\",\"id\":123,\"beforeField\":\"\",\"afterField\":\"\",\"value\":\"\",\"parentType\":\"list\",\"element_templates\":[\"listselect\",\"input\"],\"old_classname\":\"list-select\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":6,\"idAttribute\":\"id\",\"label\":\"Cidade\",\"type\":\"city\",\"key\":\"city_1648115394347\",\"label_pos\":\"left\",\"required\":1,\"default\":\"\",\"placeholder\":\"\",\"container_class\":\"\",\"element_class\":\"\",\"input_limit\":\"\",\"input_limit_type\":\"characters\",\"input_limit_msg\":\"Caracteres restantes\",\"manual_key\":\"\",\"admin_label\":\"\",\"help_text\":\"\",\"mask\":\"\",\"custom_mask\":\"\",\"custom_name_attribute\":\"city\",\"personally_identifiable\":\"\",\"value\":\"\",\"drawerDisabled\":\"\",\"field_label\":\"Citt\\u00e0\",\"field_key\":\"city_1648115394347\",\"id\":114,\"beforeField\":\"\",\"afterField\":\"\",\"parentType\":\"city\",\"element_templates\":[\"city\",\"textbox\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":7,\"idAttribute\":\"id\",\"label\":\"E-mail\",\"type\":\"email\",\"key\":\"email_1648115409608\",\"label_pos\":\"left\",\"required\":1,\"default\":\"\",\"placeholder\":\"\",\"container_class\":\"\",\"element_class\":\"\",\"admin_label\":\"\",\"help_text\":\"\",\"custom_name_attribute\":\"email\",\"personally_identifiable\":1,\"value\":\"\",\"drawerDisabled\":\"\",\"field_label\":\"Email\",\"field_key\":\"email_1648115409608\",\"id\":115,\"beforeField\":\"\",\"afterField\":\"\",\"parentType\":\"email\",\"element_templates\":[\"email\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":8,\"idAttribute\":\"id\",\"label\":\"Telefone\",\"type\":\"phone\",\"key\":\"phone_1648116570469\",\"label_pos\":\"left\",\"required\":\"\",\"default\":\"\",\"placeholder\":\"\",\"container_class\":\"\",\"element_class\":\"\",\"input_limit\":\"\",\"input_limit_type\":\"characters\",\"input_limit_msg\":\"Caracteres restantes\",\"manual_key\":\"\",\"admin_label\":\"\",\"help_text\":\"\",\"mask\":\"\",\"custom_mask\":\"\",\"custom_name_attribute\":\"phone\",\"personally_identifiable\":1,\"value\":\"\",\"drawerDisabled\":\"\",\"field_label\":\"Telefono\",\"field_key\":\"phone_1648116570469\",\"id\":122,\"beforeField\":\"\",\"afterField\":\"\",\"parentType\":\"textbox\",\"element_templates\":[\"tel\",\"textbox\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":9,\"idAttribute\":\"id\",\"label\":\"Divisor\",\"type\":\"hr\",\"container_class\":\"\",\"element_class\":\"\",\"key\":\"hr_1648115499923\",\"drawerDisabled\":\"\",\"field_label\":\"Divisore\",\"field_key\":\"hr_1648115499923\",\"admin_label\":\"\",\"id\":116,\"beforeField\":\"\",\"afterField\":\"\",\"value\":\"\",\"label_pos\":\"left\",\"parentType\":\"hr\",\"element_templates\":[\"hr\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":10,\"idAttribute\":\"id\",\"label\":\"Tipo de interven\\u00e7\\u00e3o\",\"type\":\"listselect\",\"key\":\"tipologia_di_intervento_1744366483774\",\"label_pos\":\"left\",\"required\":\"\",\"container_class\":\"\",\"element_class\":\"\",\"admin_label\":\"\",\"help_text\":\"\",\"drawerDisabled\":\"\",\"field_label\":\"Tipologia di intervento\",\"field_key\":\"tipologia_di_intervento_1744366483774\",\"options\":[{\"errors\":[],\"max_options\":0,\"label\":\"Obras de constru\\u00e7\\u00e3o civil\",\"value\":\"cantiere-di-edilizia-civile\",\"calc\":\"\",\"selected\":0,\"order\":0,\"settingModel\":{\"settings\":false,\"hide_merge_tags\":false,\"error\":false,\"name\":\"options\",\"type\":\"option-repeater\",\"label\":\"Options <a href=\\\"#\\\" class=\\\"nf-add-new\\\">Aggiungi nuovo<\\\/a> <a href=\\\"#\\\" class=\\\"extra nf-open-import-tooltip\\\"><i class=\\\"fa fa-sign-in\\\" aria-hidden=\\\"true\\\"><\\\/i> Importa<\\\/a>\",\"width\":\"full\",\"group\":\"\",\"value\":[{\"label\":\"Uno\",\"value\":\"uno\",\"calc\":\"\",\"selected\":0,\"order\":0},{\"label\":\"Due\",\"value\":\"due\",\"calc\":\"\",\"selected\":0,\"order\":1},{\"label\":\"Tre\",\"value\":\"tre\",\"calc\":\"\",\"selected\":0,\"order\":2}],\"columns\":{\"label\":{\"header\":\"Etichetta\",\"default\":\"\"},\"value\":{\"header\":\"Valore\",\"default\":\"\"},\"calc\":{\"header\":\"Calcolo\",\"default\":\"\"},\"selected\":{\"header\":\"<span class=\\\"dashicons dashicons-yes\\\"><\\\/span>\",\"default\":0}}}},{\"errors\":[],\"max_options\":0,\"label\":\"Interven\\u00e7\\u00e3o de reestrutura\\u00e7\\u00e3o\\\/restauro\",\"value\":\"intervento-di-ristrutturazione-ripristino\",\"calc\":\"\",\"selected\":0,\"order\":1,\"settingModel\":{\"settings\":false,\"hide_merge_tags\":false,\"error\":false,\"name\":\"options\",\"type\":\"option-repeater\",\"label\":\"Options <a href=\\\"#\\\" class=\\\"nf-add-new\\\">Aggiungi nuovo<\\\/a> <a href=\\\"#\\\" class=\\\"extra nf-open-import-tooltip\\\"><i class=\\\"fa fa-sign-in\\\" aria-hidden=\\\"true\\\"><\\\/i> Importa<\\\/a>\",\"width\":\"full\",\"group\":\"\",\"value\":[{\"label\":\"Uno\",\"value\":\"uno\",\"calc\":\"\",\"selected\":0,\"order\":0},{\"label\":\"Due\",\"value\":\"due\",\"calc\":\"\",\"selected\":0,\"order\":1},{\"label\":\"Tre\",\"value\":\"tre\",\"calc\":\"\",\"selected\":0,\"order\":2}],\"columns\":{\"label\":{\"header\":\"Etichetta\",\"default\":\"\"},\"value\":{\"header\":\"Valore\",\"default\":\"\"},\"calc\":{\"header\":\"Calcolo\",\"default\":\"\"},\"selected\":{\"header\":\"<span class=\\\"dashicons dashicons-yes\\\"><\\\/span>\",\"default\":0}}}},{\"errors\":[],\"max_options\":0,\"label\":\"Obras de restaura\\u00e7\\u00e3o monumental\",\"value\":\"cantiere-di-restauro-monumentale\",\"calc\":\"\",\"selected\":0,\"order\":2,\"settingModel\":{\"settings\":false,\"hide_merge_tags\":false,\"error\":false,\"name\":\"options\",\"type\":\"option-repeater\",\"label\":\"Options <a href=\\\"#\\\" class=\\\"nf-add-new\\\">Aggiungi nuovo<\\\/a> <a href=\\\"#\\\" class=\\\"extra nf-open-import-tooltip\\\"><i class=\\\"fa fa-sign-in\\\" aria-hidden=\\\"true\\\"><\\\/i> Importa<\\\/a>\",\"width\":\"full\",\"group\":\"\",\"value\":[{\"label\":\"Uno\",\"value\":\"uno\",\"calc\":\"\",\"selected\":0,\"order\":0},{\"label\":\"Due\",\"value\":\"due\",\"calc\":\"\",\"selected\":0,\"order\":1},{\"label\":\"Tre\",\"value\":\"tre\",\"calc\":\"\",\"selected\":0,\"order\":2}],\"columns\":{\"label\":{\"header\":\"Etichetta\",\"default\":\"\"},\"value\":{\"header\":\"Valore\",\"default\":\"\"},\"calc\":{\"header\":\"Calcolo\",\"default\":\"\"},\"selected\":{\"header\":\"<span class=\\\"dashicons dashicons-yes\\\"><\\\/span>\",\"default\":0}}}}],\"id\":124,\"beforeField\":\"\",\"afterField\":\"\",\"value\":\"\",\"parentType\":\"list\",\"element_templates\":[\"listselect\",\"input\"],\"old_classname\":\"list-select\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":11,\"idAttribute\":\"id\",\"label\":\"Escreva quaisquer pedidos adicionais ou detalhes sobre a interven\\u00e7\\u00e3o a realizar.\",\"type\":\"textarea\",\"key\":\"scrivi_ulteriori_richieste_o_dettagli_sull_intervento_da_effettuare_1648115743086\",\"label_pos\":\"left\",\"required\":\"\",\"default\":\"\",\"placeholder\":\"\",\"container_class\":\"\",\"element_class\":\"\",\"input_limit\":\"\",\"input_limit_type\":\"characters\",\"input_limit_msg\":\"Caracteres restantes\",\"manual_key\":\"\",\"admin_label\":\"\",\"help_text\":\"\",\"textarea_rte\":\"\",\"disable_rte_mobile\":\"\",\"textarea_media\":\"\",\"value\":\"\",\"drawerDisabled\":\"\",\"field_label\":\"Scrivi ulteriori richieste o dettagli sull'intervento da effettuare\",\"field_key\":\"scrivi_ulteriori_richieste_o_dettagli_sull_intervento_da_effettuare_1648115743086\",\"id\":118,\"beforeField\":\"\",\"afterField\":\"\",\"parentType\":\"textarea\",\"element_templates\":[\"textarea\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":12,\"idAttribute\":\"id\",\"label\":\"Divisor\",\"type\":\"hr\",\"container_class\":\"\",\"element_class\":\"\",\"key\":\"hr_1648115753742\",\"drawerDisabled\":\"\",\"field_label\":\"Divisore\",\"field_key\":\"hr_1648115753742\",\"admin_label\":\"\",\"id\":119,\"beforeField\":\"\",\"afterField\":\"\",\"value\":\"\",\"label_pos\":\"left\",\"parentType\":\"hr\",\"element_templates\":[\"hr\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":13,\"idAttribute\":\"id\",\"label\":\"Autorizo o tratamento dos meus dados pessoais nos termos da Lei 196\\\/03 sobre privacidade.\",\"type\":\"checkbox\",\"key\":\"autorizzo_il_trattamento_dei_miei_dati_personali_ai_sensi_della_legge_196_03_sulla_privacy_1648115780227\",\"label_pos\":\"right\",\"required\":1,\"container_class\":\"\",\"element_class\":\"\",\"manual_key\":\"\",\"admin_label\":\"\",\"help_text\":\"\",\"default_value\":\"unchecked\",\"checked_value\":\"Selezionato\",\"unchecked_value\":\"Deselezionato\",\"checked_calc_value\":\"\",\"unchecked_calc_value\":\"\",\"drawerDisabled\":\"\",\"field_label\":\"Autorizzo Il Trattamento Dei Miei Dati Personali Ai Sensi Della Legge 196\\\/03 Sulla Privacy\",\"field_key\":\"autorizzo_il_trattamento_dei_miei_dati_personali_ai_sensi_della_legge_196_03_sulla_privacy_1648115780227\",\"id\":120,\"beforeField\":\"\",\"afterField\":\"\",\"value\":\"\",\"parentType\":\"checkbox\",\"element_templates\":[\"checkbox\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":14,\"idAttribute\":\"id\",\"type\":\"submit\",\"label\":\"Enviar pedido\",\"processing_label\":\"Pedido em fase de envio\",\"container_class\":\"\",\"element_class\":\"\",\"key\":\"invia_richiesta_1648116001680\",\"drawerDisabled\":\"\",\"field_label\":\"Invia Richiesta\",\"field_key\":\"invia_richiesta_1648116001680\",\"admin_label\":\"\",\"id\":121,\"beforeField\":\"\",\"afterField\":\"\",\"value\":\"\",\"label_pos\":\"left\",\"parentType\":\"textbox\",\"element_templates\":[\"submit\",\"button\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap-no-label\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":15,\"idAttribute\":\"id\",\"type\":\"hidden\",\"label\":\"Nascondi\",\"key\":\"hidden_1754315696073\",\"default\":\"\",\"admin_label\":\"\",\"id\":126,\"beforeField\":\"\",\"afterField\":\"\",\"value\":\"\",\"label_pos\":\"left\",\"parentType\":\"hidden\",\"element_templates\":[\"hidden\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap-no-label\"}];nfForms.push(form);<\/script>\n        [\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>DETERGENTE NEUTRO DE MANUTEN\u00c7\u00c3O E POLIMENTO PARA PAVIMENTOS POLIDOS OU PROTEGIDOS COM ACABAMENTOS<\/p>\n","protected":false},"featured_media":10863,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_exactmetrics_skip_tracking":false},"product_brand":[],"product_cat":[563,536],"product_tag":[584],"class_list":["post-14190","product","type-product","status-publish","has-post-thumbnail","product_cat-pavimentazioni-in-gres-pt","product_cat-pavimentazioni-manutentori-pt","product_tag-sicuro_operatore-pt","pa_linea-prodotto-pavimentazioni-pt","pa_materiali-di-applicazione-gres-porcellanato-pt","first","instock","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/www.circhimica.it\/pt-pt\/wp-json\/wp\/v2\/product\/14190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.circhimica.it\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.circhimica.it\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.circhimica.it\/pt-pt\/wp-json\/wp\/v2\/comments?post=14190"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.circhimica.it\/pt-pt\/wp-json\/wp\/v2\/media\/10863"}],"wp:attachment":[{"href":"https:\/\/www.circhimica.it\/pt-pt\/wp-json\/wp\/v2\/media?parent=14190"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.circhimica.it\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=14190"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.circhimica.it\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=14190"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.circhimica.it\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=14190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}