{"id":3225,"date":"2018-01-30T18:01:37","date_gmt":"2018-01-30T17:01:37","guid":{"rendered":"http:\/\/www.circhimica.it\/?post_type=product&#038;p=3225"},"modified":"2025-09-19T15:49:37","modified_gmt":"2025-09-19T13:49:37","slug":"malta-osmotica","status":"publish","type":"product","link":"https:\/\/www.circhimica.it\/pt-pt\/prodotto\/malta-osmotica\/","title":{"rendered":"MALTA OSMOTICA"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; bottom_margin=&#8221;0&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_cta btn_style=&#8221;arrow-animation&#8221; heading_tag=&#8221;h3&#8243; button_color=&#8221;default&#8221; button_border_thickness=&#8221;0px&#8221; link_type=&#8221;regular&#8221; alignment=&#8221;left&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; display=&#8221;inline&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; link_text=&#8221;DESCRIZIONE DEL PRODOTTO&#8221; margin_right=&#8221;20&#8243; url=&#8221;#descrizione&#8221;][nectar_cta btn_style=&#8221;arrow-animation&#8221; heading_tag=&#8221;h3&#8243; button_color=&#8221;default&#8221; button_border_thickness=&#8221;0px&#8221; link_type=&#8221;regular&#8221; alignment=&#8221;left&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; display=&#8221;inline&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; link_text=&#8221;SCARICA IL MATERIALE TECNICO&#8221; margin_right=&#8221;20&#8243; url=&#8221;#downloads&#8221;][nectar_cta btn_style=&#8221;arrow-animation&#8221; heading_tag=&#8221;h3&#8243; button_color=&#8221;default&#8221; button_border_thickness=&#8221;0px&#8221; link_type=&#8221;regular&#8221; alignment=&#8221;left&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; display=&#8221;inline&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; link_text=&#8221;RICHIEDI MAGGIORI INFORMAZIONI&#8221; margin_right=&#8221;20&#8243; url=&#8221;#form&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#dff1fb&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;15&#8243; bottom_padding=&#8221;10&#8243; top_margin=&#8221;5&#8243; bottom_margin=&#8221;20&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;4810&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; img_link=&#8221;\/linea-facciate\/&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;right&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;right&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;none&#8221; equal_height=&#8221;yes&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;GAMMA&#8221; font_container=&#8221;tag:h2|font_size:1.5em|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;MATERIALI COMPATIBILI&#8221; font_container=&#8221;tag:h2|font_size:1.5em|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;MODALIT\u00c0 DI APPLICAZIONE&#8221; font_container=&#8221;tag:h2|font_size:1.5em|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;custom&#8221; column_margin_custom=&#8221;3px&#8221; equal_height=&#8221;yes&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;12906&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; img_link=&#8221;\/gamma\/deumidificazione\/&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h6 style=\"text-align: center;\"><a href=\"\/gamma\/deumidificazione\/\">DEUMIDIFICAZIONE<\/a><\/h6>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;12528&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; img_link=&#8221;\/materiali-di-applicazione\/mattoni\/&#8221;][vc_column_text css=&#8221;.vc_custom_1753946391736{margin-bottom: 8px !important;}&#8221; text_direction=&#8221;default&#8221;]\n<h6 style=\"text-align: center;\"><a href=\"\/materiali-di-applicazione\/mattoni\/\">MATTONI<\/a><\/h6>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;12921&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; img_link=&#8221;\/materiali-di-applicazione\/intonaci\/&#8221;][vc_column_text css=&#8221;.vc_custom_1753946440336{margin-bottom: 8px !important;}&#8221; text_direction=&#8221;default&#8221;]\n<h6 style=\"text-align: center;\"><a href=\"\/materiali-di-applicazione\/intonaci\/\">INTONACI<\/a><\/h6>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;12538&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h6 style=\"text-align: center;\">SPATOLA<\/h6>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;descrizione&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;DESCRIZIONE DEL PRODOTTO&#8221; font_container=&#8221;tag:h2|font_size:1.5em|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]Impermeabilizzante cementizio applicabile a pennello idoneo all\u2019uso sia in spinta idrostatica negativa che positiva. Permette l\u2019<strong>impermeabilizzazione rigida di superfici in calcestruzzo o murature<\/strong>, sotto o sopra terra, quali vasche, muri di fondazione, cantine e fosse d\u2019ascensore.[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;none&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#dff1fb&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;10&#8243; bottom_padding=&#8221;5&#8243; left_padding_desktop=&#8221;20&#8243; right_padding_desktop=&#8221;20&#8243; bottom_margin=&#8221;10&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;I VANTAGGI DI MALTA OSMOTICA&#8221; font_container=&#8221;tag:h2|font_size:1.5em|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;]<div class=\"nectar-fancy-ul\" data-list-icon=\"fa fa-plus\" data-animation=\"false\" data-animation-delay=\"0\" data-color=\"extra-color-2\" data-spacing=\"10px\" data-alignment=\"left\"> \n<ul>\n<li>Applicazione semplice e rapida con pennellessa o spazzolone<\/li>\n<li><i class=\"icon-default-style fa fa-plus extra-color-2\"><\/i>Per utilizzi sia in interno che in esterno<\/li>\n<li><i class=\"icon-default-style fa fa-plus extra-color-2\"><\/i>Particolarmente resistente all\u2019abrasione e agli urti<\/li>\n<li><i class=\"icon-default-style fa fa-plus extra-color-2\"><\/i>Ottime prestazioni di impermeabilizzazione all\u2019acqua<\/li>\n<\/ul>\n <\/div>[\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#dff1fb&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;10&#8243; bottom_padding=&#8221;20&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;downloads&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_custom_heading text=&#8221;DOWNLOADS &#8211; MATERIALE TECNICO E PROMOZIONALE&#8221; font_container=&#8221;tag:h2|font_size:1.5em|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][vc_column_text css=&#8221;.vc_custom_1744384490122{padding-right: 30px !important;}&#8221; text_direction=&#8221;default&#8221;]Puoi scaricare in qualunque momento il nostro materiale tecnico aggiornato, <strong>in formato PDF, in tutte le lingue disponibili per un determinato prodotto<\/strong>.<\/p>\n<p>Se invece hai bisogno di <strong>informazioni pi\u00f9 dettagliate<\/strong> o della nostra <strong>assistenza tecnica diretta<\/strong>, ti preghiamo di inviarci una richiesta specifica compilando il <strong>form<\/strong> sottostante.[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;SCHEDA TECNICA&#8221; font_container=&#8221;tag:h2|font_size:1.5em|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;center&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;12463&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; img_link_target=&#8221;_blank&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; img_link=&#8221;http:\/\/www.circhimica.it\/wp-content\/uploads\/2018\/03\/MALTA-OSMOTICA.pdf&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;form&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;RICHIEDI SUBITO MAGGIORI INFORMAZIONI &#8211; COMPILA QUESTO FORM&#8221; font_container=&#8221;tag:h1|font_size:1.5em|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;]<noscript class=\"ninja-forms-noscript-message\">\n\tAviso: Este conte\u00fado necessita do JavaScript.<\/noscript>\n<div id=\"nf-form-10-cont\" class=\"nf-form-cont\" aria-live=\"polite\" aria-labelledby=\"nf-form-title-10\" aria-describedby=\"nf-form-errors-10\" role=\"form\">\n\n    <div class=\"nf-loading-spinner\"><\/div>\n\n<\/div>\n        <!-- That data is being printed as a workaround to page builders reordering the order of the scripts loaded-->\n        <script>var formDisplay=1;var nfForms=nfForms||[];var form=[];form.id='10';form.settings={\"objectType\":\"Form Setting\",\"editActive\":true,\"title\":\"SOLICITA\\u00c7\\u00c3O DE INFORMA\\u00c7\\u00d5ES - Geral\",\"created_at\":\"2025-08-04 15:46:38\",\"default_label_pos\":\"left\",\"show_title\":\"0\",\"clear_complete\":\"1\",\"hide_complete\":\"1\",\"logged_in\":\"\",\"wrapper_class\":\"\",\"element_class\":\"\",\"key\":\"\",\"add_submit\":\"1\",\"changeEmailErrorMsg\":\"Introduza um endere\\u00e7o de correio eletr\\u00f3nico v\\u00e1lido!\",\"changeDateErrorMsg\":\"Please enter a valid date!\",\"confirmFieldErrorMsg\":\"Estes campos n\\u00e3o coincidem!\",\"fieldNumberNumMinError\":\"Erro de n\\u00famero m\\u00ednimo\",\"fieldNumberNumMaxError\":\"Erro de n\\u00famero m\\u00e1ximo\",\"fieldNumberIncrementBy\":\"Aumente em \",\"formErrorsCorrectErrors\":\"Corrija os erros antes de submeter este formul\\u00e1rio.\",\"validateRequiredField\":\"Este campo \\u00e9 obrigat\\u00f3rio.\",\"honeypotHoneypotError\":\"Erro do pote de mel\",\"fieldsMarkedRequired\":\"Os campos assinalados com um <span class=\\\"ninja-forms-req-symbol\\\">*<\\\/span> s\\u00e3o obrigat\\u00f3rios\",\"currency\":\"\",\"repeatable_fieldsets\":\"\",\"unique_field_error\":\"Um formul\\u00e1rio com este valor j\\u00e1 foi enviado.\",\"not_logged_in_msg\":\"\",\"sub_limit_msg\":\"O formul\\u00e1rio atingiu o limite de envios.\",\"calculations\":[],\"formContentData\":[\"nb_i_campi_contrassegnati_con_sono_obbligatori_1648116034111\",\"nome_e_cognome_o_ragione_sociale_1648115325577\",\"tipologia_di_impresa_cliente_1744366418935\",\"city_1648115394347\",\"email_1648115409608\",\"phone_1648116570469\",\"hr_1648115499923\",\"tipologia_di_intervento_1744366483774\",\"scrivi_ulteriori_richieste_o_dettagli_sull_intervento_da_effettuare_1648115743086\",\"hr_1648115753742\",\"autorizzo_il_trattamento_dei_miei_dati_personali_ai_sensi_della_legge_196_03_sulla_privacy_1648115780227\",\"invia_richiesta_1648116001680\",\"hidden_1754315696073\"],\"drawerDisabled\":false,\"form_title_heading_level\":\"4\",\"allow_public_link\":0,\"embed_form\":\"\",\"objectDomain\":\"calculations\",\"ninjaForms\":\"Ninja Forms\",\"fieldTextareaRTEInsertLink\":\"Inserir hiperliga\\u00e7\\u00e3o\",\"fieldTextareaRTEInsertMedia\":\"Inserir multim\\u00e9dia\",\"fieldTextareaRTESelectAFile\":\"Selecione um ficheiro\",\"tableInsertRowAbove\":\"Insert Row Above\",\"tableInsertRowBelow\":\"Insert Row Below\",\"tableInsertColumnLeft\":\"Insert Column Left\",\"tableInsertColumnRight\":\"Insert Column Right\",\"tableDeleteRow\":\"Delete Row\",\"tableDeleteColumn\":\"Delete Column\",\"tableDeleteTable\":\"Delete Table\",\"tableLegacyNotice\":\"This content has tables in the old editor format. Custom styles are preserved until converted. Editing will update to the new format.\",\"tableLegacyConvert\":\"Convert Now\",\"tableInsertTable\":\"Insert Table\",\"dismiss\":\"Ignorar\",\"insertLink\":\"Inserir hiperliga\\u00e7\\u00e3o\",\"formHoneypot\":\"Se for humano e estiver a ver este campo, deixe-o em branco.\",\"fileUploadOldCodeFileUploadInProgress\":\"Carregamento do ficheiro em curso.\",\"fileUploadOldCodeFileUpload\":\"CARREGAMENTO DO FICHEIRO\",\"currencySymbol\":\"&#36;\",\"thousands_sep\":\".\",\"decimal_point\":\",\",\"siteLocale\":\"pt_PT\",\"dateFormat\":\"m\\\/d\\\/Y\",\"startOfWeek\":\"1\",\"of\":\"de\",\"previousMonth\":\"Previous Month\",\"nextMonth\":\"Next Month\",\"months\":[\"January\",\"February\",\"March\",\"April\",\"May\",\"June\",\"July\",\"August\",\"September\",\"October\",\"November\",\"December\"],\"monthsShort\":[\"Jan\",\"Feb\",\"Mar\",\"Apr\",\"May\",\"Jun\",\"Jul\",\"Aug\",\"Sep\",\"Oct\",\"Nov\",\"Dec\"],\"weekdays\":[\"Sunday\",\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\"],\"weekdaysShort\":[\"Sun\",\"Mon\",\"Tue\",\"Wed\",\"Thu\",\"Fri\",\"Sat\"],\"weekdaysMin\":[\"Su\",\"Mo\",\"Tu\",\"We\",\"Th\",\"Fr\",\"Sa\"],\"recaptchaConsentMissing\":\"reCaptcha validation couldn&#039;t load.\",\"recaptchaMissingCookie\":\"reCaptcha v3 validation couldn&#039;t load the cookie needed to submit the form.\",\"recaptchaConsentEvent\":\"Accept reCaptcha cookies before sending the form.\",\"currency_symbol\":\"\",\"beforeForm\":\"\",\"beforeFields\":\"\",\"afterFields\":\"\",\"afterForm\":\"\"};form.fields=[{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":3,\"idAttribute\":\"id\",\"label\":\"Os campos marcados com * s\\u00e3o obrigat\\u00f3rios\",\"type\":\"html\",\"default\":\"<p><br><\\\/p>\",\"container_class\":\"\",\"element_class\":\"\",\"key\":\"nb_i_campi_contrassegnati_con_sono_obbligatori_1648116034111\",\"drawerDisabled\":false,\"field_label\":\"NB I campi contrassegnati con * sono obbligatori\",\"field_key\":\"nb_i_campi_contrassegnati_con_sono_obbligatori_1648116034111\",\"admin_label\":\"\",\"id\":117,\"beforeField\":\"\",\"afterField\":\"\",\"value\":\"<p><br><\\\/p>\",\"label_pos\":\"left\",\"parentType\":\"html\",\"element_templates\":[\"html\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":4,\"idAttribute\":\"id\",\"label\":\"Nome e Apelido ou Raz\\u00e3o Social\",\"type\":\"firstname\",\"key\":\"nome_e_cognome_o_ragione_sociale_1648115325577\",\"label_pos\":\"left\",\"required\":1,\"default\":\"\",\"placeholder\":\"\",\"container_class\":\"\",\"element_class\":\"\",\"admin_label\":\"\",\"help_text\":\"\",\"custom_name_attribute\":\"fname\",\"personally_identifiable\":1,\"value\":\"\",\"drawerDisabled\":\"\",\"field_label\":\"Nome e Cognome o Ragione Sociale\",\"field_key\":\"nome_e_cognome_o_ragione_sociale_1648115325577\",\"id\":113,\"beforeField\":\"\",\"afterField\":\"\",\"parentType\":\"firstname\",\"element_templates\":[\"firstname\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":5,\"idAttribute\":\"id\",\"label\":\"Tipo de empresa\\\/cliente\",\"type\":\"listselect\",\"key\":\"tipologia_di_impresa_cliente_1744366418935\",\"label_pos\":\"left\",\"required\":1,\"options\":[{\"errors\":[],\"max_options\":0,\"label\":\"Empresa de constru\\u00e7\\u00e3o civil\",\"value\":\"impresa-edile\",\"calc\":\"\",\"selected\":0,\"order\":0,\"settingModel\":{\"settings\":false,\"hide_merge_tags\":false,\"error\":false,\"name\":\"options\",\"type\":\"option-repeater\",\"label\":\"Options <a href=\\\"#\\\" class=\\\"nf-add-new\\\">Aggiungi nuovo<\\\/a> <a href=\\\"#\\\" class=\\\"extra nf-open-import-tooltip\\\"><i class=\\\"fa fa-sign-in\\\" aria-hidden=\\\"true\\\"><\\\/i> Importa<\\\/a>\",\"width\":\"full\",\"group\":\"\",\"value\":[{\"label\":\"Uno\",\"value\":\"uno\",\"calc\":\"\",\"selected\":0,\"order\":0},{\"label\":\"Due\",\"value\":\"due\",\"calc\":\"\",\"selected\":0,\"order\":1},{\"label\":\"Tre\",\"value\":\"tre\",\"calc\":\"\",\"selected\":0,\"order\":2}],\"columns\":{\"label\":{\"header\":\"Etichetta\",\"default\":\"\"},\"value\":{\"header\":\"Valore\",\"default\":\"\"},\"calc\":{\"header\":\"Calcolo\",\"default\":\"\"},\"selected\":{\"header\":\"<span class=\\\"dashicons dashicons-yes\\\"><\\\/span>\",\"default\":0}}}},{\"errors\":[],\"max_options\":0,\"label\":\"Empresa de Restauro\",\"value\":\"impresa-di-restauro\",\"calc\":\"\",\"selected\":0,\"order\":1,\"settingModel\":{\"settings\":false,\"hide_merge_tags\":false,\"error\":false,\"name\":\"options\",\"type\":\"option-repeater\",\"label\":\"Options <a href=\\\"#\\\" class=\\\"nf-add-new\\\">Aggiungi nuovo<\\\/a> <a href=\\\"#\\\" class=\\\"extra nf-open-import-tooltip\\\"><i class=\\\"fa fa-sign-in\\\" aria-hidden=\\\"true\\\"><\\\/i> Importa<\\\/a>\",\"width\":\"full\",\"group\":\"\",\"value\":[{\"label\":\"Uno\",\"value\":\"uno\",\"calc\":\"\",\"selected\":0,\"order\":0},{\"label\":\"Due\",\"value\":\"due\",\"calc\":\"\",\"selected\":0,\"order\":1},{\"label\":\"Tre\",\"value\":\"tre\",\"calc\":\"\",\"selected\":0,\"order\":2}],\"columns\":{\"label\":{\"header\":\"Etichetta\",\"default\":\"\"},\"value\":{\"header\":\"Valore\",\"default\":\"\"},\"calc\":{\"header\":\"Calcolo\",\"default\":\"\"},\"selected\":{\"header\":\"<span class=\\\"dashicons dashicons-yes\\\"><\\\/span>\",\"default\":0}}}},{\"errors\":[],\"max_options\":0,\"label\":\"Projetista \\\/ Profissional\",\"value\":\"progettista-professionista\",\"calc\":\"\",\"selected\":0,\"order\":2,\"settingModel\":{\"settings\":false,\"hide_merge_tags\":false,\"error\":false,\"name\":\"options\",\"type\":\"option-repeater\",\"label\":\"Options <a href=\\\"#\\\" class=\\\"nf-add-new\\\">Aggiungi nuovo<\\\/a> <a href=\\\"#\\\" class=\\\"extra nf-open-import-tooltip\\\"><i class=\\\"fa fa-sign-in\\\" aria-hidden=\\\"true\\\"><\\\/i> Importa<\\\/a>\",\"width\":\"full\",\"group\":\"\",\"value\":[{\"label\":\"Uno\",\"value\":\"uno\",\"calc\":\"\",\"selected\":0,\"order\":0},{\"label\":\"Due\",\"value\":\"due\",\"calc\":\"\",\"selected\":0,\"order\":1},{\"label\":\"Tre\",\"value\":\"tre\",\"calc\":\"\",\"selected\":0,\"order\":2}],\"columns\":{\"label\":{\"header\":\"Etichetta\",\"default\":\"\"},\"value\":{\"header\":\"Valore\",\"default\":\"\"},\"calc\":{\"header\":\"Calcolo\",\"default\":\"\"},\"selected\":{\"header\":\"<span class=\\\"dashicons dashicons-yes\\\"><\\\/span>\",\"default\":0}}}},{\"errors\":[],\"max_options\":0,\"order\":3,\"new\":false,\"options\":[],\"label\":\"Rivenditore\",\"value\":\"rivenditore\",\"calc\":\"\",\"selected\":0,\"settingModel\":{\"settings\":false,\"hide_merge_tags\":false,\"error\":false,\"name\":\"options\",\"type\":\"option-repeater\",\"label\":\"Options <a href=\\\"#\\\" class=\\\"nf-add-new\\\">Aggiungi nuovo<\\\/a> <a href=\\\"#\\\" class=\\\"extra nf-open-import-tooltip\\\"><i class=\\\"fa fa-sign-in\\\" aria-hidden=\\\"true\\\"><\\\/i> Importa<\\\/a>\",\"width\":\"full\",\"group\":\"\",\"value\":[{\"label\":\"Uno\",\"value\":\"uno\",\"calc\":\"\",\"selected\":0,\"order\":0},{\"label\":\"Due\",\"value\":\"due\",\"calc\":\"\",\"selected\":0,\"order\":1},{\"label\":\"Tre\",\"value\":\"tre\",\"calc\":\"\",\"selected\":0,\"order\":2}],\"columns\":{\"label\":{\"header\":\"Etichetta\",\"default\":\"\"},\"value\":{\"header\":\"Valore\",\"default\":\"\"},\"calc\":{\"header\":\"Calcolo\",\"default\":\"\"},\"selected\":{\"header\":\"<span class=\\\"dashicons dashicons-yes\\\"><\\\/span>\",\"default\":0}}}},{\"errors\":[],\"max_options\":0,\"order\":4,\"new\":false,\"options\":[],\"label\":\"Cliente particular\",\"value\":\"cliente-privato\",\"calc\":\"\",\"selected\":0,\"settingModel\":{\"settings\":false,\"hide_merge_tags\":false,\"error\":false,\"name\":\"options\",\"type\":\"option-repeater\",\"label\":\"Options <a href=\\\"#\\\" class=\\\"nf-add-new\\\">Aggiungi nuovo<\\\/a> <a href=\\\"#\\\" class=\\\"extra nf-open-import-tooltip\\\"><i class=\\\"fa fa-sign-in\\\" aria-hidden=\\\"true\\\"><\\\/i> Importa<\\\/a>\",\"width\":\"full\",\"group\":\"\",\"value\":[{\"label\":\"Uno\",\"value\":\"uno\",\"calc\":\"\",\"selected\":0,\"order\":0},{\"label\":\"Due\",\"value\":\"due\",\"calc\":\"\",\"selected\":0,\"order\":1},{\"label\":\"Tre\",\"value\":\"tre\",\"calc\":\"\",\"selected\":0,\"order\":2}],\"columns\":{\"label\":{\"header\":\"Etichetta\",\"default\":\"\"},\"value\":{\"header\":\"Valore\",\"default\":\"\"},\"calc\":{\"header\":\"Calcolo\",\"default\":\"\"},\"selected\":{\"header\":\"<span class=\\\"dashicons dashicons-yes\\\"><\\\/span>\",\"default\":0}}}}],\"container_class\":\"\",\"element_class\":\"\",\"admin_label\":\"\",\"help_text\":\"\",\"drawerDisabled\":\"\",\"field_label\":\"Tipologia di impresa \\\/ cliente\",\"field_key\":\"tipologia_di_impresa_cliente_1744366418935\",\"id\":123,\"beforeField\":\"\",\"afterField\":\"\",\"value\":\"\",\"parentType\":\"list\",\"element_templates\":[\"listselect\",\"input\"],\"old_classname\":\"list-select\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":6,\"idAttribute\":\"id\",\"label\":\"Cidade\",\"type\":\"city\",\"key\":\"city_1648115394347\",\"label_pos\":\"left\",\"required\":1,\"default\":\"\",\"placeholder\":\"\",\"container_class\":\"\",\"element_class\":\"\",\"input_limit\":\"\",\"input_limit_type\":\"characters\",\"input_limit_msg\":\"Caracteres restantes\",\"manual_key\":\"\",\"admin_label\":\"\",\"help_text\":\"\",\"mask\":\"\",\"custom_mask\":\"\",\"custom_name_attribute\":\"city\",\"personally_identifiable\":\"\",\"value\":\"\",\"drawerDisabled\":\"\",\"field_label\":\"Citt\\u00e0\",\"field_key\":\"city_1648115394347\",\"id\":114,\"beforeField\":\"\",\"afterField\":\"\",\"parentType\":\"city\",\"element_templates\":[\"city\",\"textbox\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":7,\"idAttribute\":\"id\",\"label\":\"E-mail\",\"type\":\"email\",\"key\":\"email_1648115409608\",\"label_pos\":\"left\",\"required\":1,\"default\":\"\",\"placeholder\":\"\",\"container_class\":\"\",\"element_class\":\"\",\"admin_label\":\"\",\"help_text\":\"\",\"custom_name_attribute\":\"email\",\"personally_identifiable\":1,\"value\":\"\",\"drawerDisabled\":\"\",\"field_label\":\"Email\",\"field_key\":\"email_1648115409608\",\"id\":115,\"beforeField\":\"\",\"afterField\":\"\",\"parentType\":\"email\",\"element_templates\":[\"email\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":8,\"idAttribute\":\"id\",\"label\":\"Telefone\",\"type\":\"phone\",\"key\":\"phone_1648116570469\",\"label_pos\":\"left\",\"required\":\"\",\"default\":\"\",\"placeholder\":\"\",\"container_class\":\"\",\"element_class\":\"\",\"input_limit\":\"\",\"input_limit_type\":\"characters\",\"input_limit_msg\":\"Caracteres restantes\",\"manual_key\":\"\",\"admin_label\":\"\",\"help_text\":\"\",\"mask\":\"\",\"custom_mask\":\"\",\"custom_name_attribute\":\"phone\",\"personally_identifiable\":1,\"value\":\"\",\"drawerDisabled\":\"\",\"field_label\":\"Telefono\",\"field_key\":\"phone_1648116570469\",\"id\":122,\"beforeField\":\"\",\"afterField\":\"\",\"parentType\":\"textbox\",\"element_templates\":[\"tel\",\"textbox\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":9,\"idAttribute\":\"id\",\"label\":\"Divisor\",\"type\":\"hr\",\"container_class\":\"\",\"element_class\":\"\",\"key\":\"hr_1648115499923\",\"drawerDisabled\":\"\",\"field_label\":\"Divisore\",\"field_key\":\"hr_1648115499923\",\"admin_label\":\"\",\"id\":116,\"beforeField\":\"\",\"afterField\":\"\",\"value\":\"\",\"label_pos\":\"left\",\"parentType\":\"hr\",\"element_templates\":[\"hr\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":10,\"idAttribute\":\"id\",\"label\":\"Tipo de interven\\u00e7\\u00e3o\",\"type\":\"listselect\",\"key\":\"tipologia_di_intervento_1744366483774\",\"label_pos\":\"left\",\"required\":\"\",\"container_class\":\"\",\"element_class\":\"\",\"admin_label\":\"\",\"help_text\":\"\",\"drawerDisabled\":\"\",\"field_label\":\"Tipologia di intervento\",\"field_key\":\"tipologia_di_intervento_1744366483774\",\"options\":[{\"errors\":[],\"max_options\":0,\"label\":\"Obras de constru\\u00e7\\u00e3o civil\",\"value\":\"cantiere-di-edilizia-civile\",\"calc\":\"\",\"selected\":0,\"order\":0,\"settingModel\":{\"settings\":false,\"hide_merge_tags\":false,\"error\":false,\"name\":\"options\",\"type\":\"option-repeater\",\"label\":\"Options <a href=\\\"#\\\" class=\\\"nf-add-new\\\">Aggiungi nuovo<\\\/a> <a href=\\\"#\\\" class=\\\"extra nf-open-import-tooltip\\\"><i class=\\\"fa fa-sign-in\\\" aria-hidden=\\\"true\\\"><\\\/i> Importa<\\\/a>\",\"width\":\"full\",\"group\":\"\",\"value\":[{\"label\":\"Uno\",\"value\":\"uno\",\"calc\":\"\",\"selected\":0,\"order\":0},{\"label\":\"Due\",\"value\":\"due\",\"calc\":\"\",\"selected\":0,\"order\":1},{\"label\":\"Tre\",\"value\":\"tre\",\"calc\":\"\",\"selected\":0,\"order\":2}],\"columns\":{\"label\":{\"header\":\"Etichetta\",\"default\":\"\"},\"value\":{\"header\":\"Valore\",\"default\":\"\"},\"calc\":{\"header\":\"Calcolo\",\"default\":\"\"},\"selected\":{\"header\":\"<span class=\\\"dashicons dashicons-yes\\\"><\\\/span>\",\"default\":0}}}},{\"errors\":[],\"max_options\":0,\"label\":\"Interven\\u00e7\\u00e3o de reestrutura\\u00e7\\u00e3o\\\/restauro\",\"value\":\"intervento-di-ristrutturazione-ripristino\",\"calc\":\"\",\"selected\":0,\"order\":1,\"settingModel\":{\"settings\":false,\"hide_merge_tags\":false,\"error\":false,\"name\":\"options\",\"type\":\"option-repeater\",\"label\":\"Options <a href=\\\"#\\\" class=\\\"nf-add-new\\\">Aggiungi nuovo<\\\/a> <a href=\\\"#\\\" class=\\\"extra nf-open-import-tooltip\\\"><i class=\\\"fa fa-sign-in\\\" aria-hidden=\\\"true\\\"><\\\/i> Importa<\\\/a>\",\"width\":\"full\",\"group\":\"\",\"value\":[{\"label\":\"Uno\",\"value\":\"uno\",\"calc\":\"\",\"selected\":0,\"order\":0},{\"label\":\"Due\",\"value\":\"due\",\"calc\":\"\",\"selected\":0,\"order\":1},{\"label\":\"Tre\",\"value\":\"tre\",\"calc\":\"\",\"selected\":0,\"order\":2}],\"columns\":{\"label\":{\"header\":\"Etichetta\",\"default\":\"\"},\"value\":{\"header\":\"Valore\",\"default\":\"\"},\"calc\":{\"header\":\"Calcolo\",\"default\":\"\"},\"selected\":{\"header\":\"<span class=\\\"dashicons dashicons-yes\\\"><\\\/span>\",\"default\":0}}}},{\"errors\":[],\"max_options\":0,\"label\":\"Obras de restaura\\u00e7\\u00e3o monumental\",\"value\":\"cantiere-di-restauro-monumentale\",\"calc\":\"\",\"selected\":0,\"order\":2,\"settingModel\":{\"settings\":false,\"hide_merge_tags\":false,\"error\":false,\"name\":\"options\",\"type\":\"option-repeater\",\"label\":\"Options <a href=\\\"#\\\" class=\\\"nf-add-new\\\">Aggiungi nuovo<\\\/a> <a href=\\\"#\\\" class=\\\"extra nf-open-import-tooltip\\\"><i class=\\\"fa fa-sign-in\\\" aria-hidden=\\\"true\\\"><\\\/i> Importa<\\\/a>\",\"width\":\"full\",\"group\":\"\",\"value\":[{\"label\":\"Uno\",\"value\":\"uno\",\"calc\":\"\",\"selected\":0,\"order\":0},{\"label\":\"Due\",\"value\":\"due\",\"calc\":\"\",\"selected\":0,\"order\":1},{\"label\":\"Tre\",\"value\":\"tre\",\"calc\":\"\",\"selected\":0,\"order\":2}],\"columns\":{\"label\":{\"header\":\"Etichetta\",\"default\":\"\"},\"value\":{\"header\":\"Valore\",\"default\":\"\"},\"calc\":{\"header\":\"Calcolo\",\"default\":\"\"},\"selected\":{\"header\":\"<span class=\\\"dashicons dashicons-yes\\\"><\\\/span>\",\"default\":0}}}}],\"id\":124,\"beforeField\":\"\",\"afterField\":\"\",\"value\":\"\",\"parentType\":\"list\",\"element_templates\":[\"listselect\",\"input\"],\"old_classname\":\"list-select\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":11,\"idAttribute\":\"id\",\"label\":\"Escreva quaisquer pedidos adicionais ou detalhes sobre a interven\\u00e7\\u00e3o a realizar.\",\"type\":\"textarea\",\"key\":\"scrivi_ulteriori_richieste_o_dettagli_sull_intervento_da_effettuare_1648115743086\",\"label_pos\":\"left\",\"required\":\"\",\"default\":\"\",\"placeholder\":\"\",\"container_class\":\"\",\"element_class\":\"\",\"input_limit\":\"\",\"input_limit_type\":\"characters\",\"input_limit_msg\":\"Caracteres restantes\",\"manual_key\":\"\",\"admin_label\":\"\",\"help_text\":\"\",\"textarea_rte\":\"\",\"disable_rte_mobile\":\"\",\"textarea_media\":\"\",\"value\":\"\",\"drawerDisabled\":\"\",\"field_label\":\"Scrivi ulteriori richieste o dettagli sull'intervento da effettuare\",\"field_key\":\"scrivi_ulteriori_richieste_o_dettagli_sull_intervento_da_effettuare_1648115743086\",\"id\":118,\"beforeField\":\"\",\"afterField\":\"\",\"parentType\":\"textarea\",\"element_templates\":[\"textarea\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":12,\"idAttribute\":\"id\",\"label\":\"Divisor\",\"type\":\"hr\",\"container_class\":\"\",\"element_class\":\"\",\"key\":\"hr_1648115753742\",\"drawerDisabled\":\"\",\"field_label\":\"Divisore\",\"field_key\":\"hr_1648115753742\",\"admin_label\":\"\",\"id\":119,\"beforeField\":\"\",\"afterField\":\"\",\"value\":\"\",\"label_pos\":\"left\",\"parentType\":\"hr\",\"element_templates\":[\"hr\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":13,\"idAttribute\":\"id\",\"label\":\"Autorizo o tratamento dos meus dados pessoais nos termos da Lei 196\\\/03 sobre privacidade.\",\"type\":\"checkbox\",\"key\":\"autorizzo_il_trattamento_dei_miei_dati_personali_ai_sensi_della_legge_196_03_sulla_privacy_1648115780227\",\"label_pos\":\"right\",\"required\":1,\"container_class\":\"\",\"element_class\":\"\",\"manual_key\":\"\",\"admin_label\":\"\",\"help_text\":\"\",\"default_value\":\"unchecked\",\"checked_value\":\"Selezionato\",\"unchecked_value\":\"Deselezionato\",\"checked_calc_value\":\"\",\"unchecked_calc_value\":\"\",\"drawerDisabled\":\"\",\"field_label\":\"Autorizzo Il Trattamento Dei Miei Dati Personali Ai Sensi Della Legge 196\\\/03 Sulla Privacy\",\"field_key\":\"autorizzo_il_trattamento_dei_miei_dati_personali_ai_sensi_della_legge_196_03_sulla_privacy_1648115780227\",\"id\":120,\"beforeField\":\"\",\"afterField\":\"\",\"value\":\"\",\"parentType\":\"checkbox\",\"element_templates\":[\"checkbox\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":14,\"idAttribute\":\"id\",\"type\":\"submit\",\"label\":\"Enviar pedido\",\"processing_label\":\"Pedido em fase de envio\",\"container_class\":\"\",\"element_class\":\"\",\"key\":\"invia_richiesta_1648116001680\",\"drawerDisabled\":\"\",\"field_label\":\"Invia Richiesta\",\"field_key\":\"invia_richiesta_1648116001680\",\"admin_label\":\"\",\"id\":121,\"beforeField\":\"\",\"afterField\":\"\",\"value\":\"\",\"label_pos\":\"left\",\"parentType\":\"textbox\",\"element_templates\":[\"submit\",\"button\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap-no-label\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":15,\"idAttribute\":\"id\",\"type\":\"hidden\",\"label\":\"Nascondi\",\"key\":\"hidden_1754315696073\",\"default\":\"\",\"admin_label\":\"\",\"id\":126,\"beforeField\":\"\",\"afterField\":\"\",\"value\":\"\",\"label_pos\":\"left\",\"parentType\":\"hidden\",\"element_templates\":[\"hidden\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap-no-label\"}];nfForms.push(form);<\/script>\n        [\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; bottom_margin=&#8221;0&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243;&#8230;<\/p>\n","protected":false},"featured_media":3227,"comment_status":"open","ping_status":"closed","template":"","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0},"product_brand":[],"product_cat":[80,138],"product_tag":[],"class_list":{"0":"post-3225","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-facciate-deumidificanti","7":"product_cat-umidita-di-risalita","8":"pa_gamma-deumidificazione","9":"pa_gamma-malte-e-polveri","10":"pa_linea-prodotto-facciate","11":"pa_materiali-di-applicazione-intonaci","13":"first","14":"instock","15":"shipping-taxable","16":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/www.circhimica.it\/pt-pt\/wp-json\/wp\/v2\/product\/3225","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.circhimica.it\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.circhimica.it\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.circhimica.it\/pt-pt\/wp-json\/wp\/v2\/comments?post=3225"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.circhimica.it\/pt-pt\/wp-json\/wp\/v2\/media\/3227"}],"wp:attachment":[{"href":"https:\/\/www.circhimica.it\/pt-pt\/wp-json\/wp\/v2\/media?parent=3225"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.circhimica.it\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=3225"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.circhimica.it\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=3225"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.circhimica.it\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=3225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}